{"id":18950,"date":"2025-12-11T11:01:20","date_gmt":"2025-12-11T10:01:20","guid":{"rendered":"https:\/\/visitpalma.com\/?post_type=tribe_events&#038;p=18950"},"modified":"2025-12-11T11:01:20","modified_gmt":"2025-12-11T10:01:20","slug":"jai-de-nadal-exposicion-de-nacimientos-y-belenes-tradicionales","status":"publish","type":"tribe_events","link":"https:\/\/visitpalma.com\/es\/event\/jai-de-nadal-exposicion-de-nacimientos-y-belenes-tradicionales\/","title":{"rendered":"Jai de Nadal: Exposici\u00f3n de Nacimientos y Belenes Tradicionales"},"content":{"rendered":"<p class=\"ft-text\">Una cita ya consolidada de la Navidad en Palma es el Jai de Nadal organizado por el <a class=\"ft-link ft-link--decoration\" href=\"https:\/\/www.diariodemallorca.es\/cultura\/2022\/04\/18\/centro-historia-militar-quiere-divulgar-65089926.html\">Centro de Historia y Cultura Militar de Baleares<\/a>, situado <strong>en la calle Sant Miquel<\/strong>. Este viernes, 11 de diciembre, por la tarde se ha inaugurado una exposici\u00f3n que cuenta con m\u00e1s de 1.100 nacimientos, cuatro grandes belenes, la muestra de reposter\u00eda y artesan\u00eda conventual, la maqueta de un tren y, pensando en los ni\u00f1os, otra locomotora con figuras de juguete.<\/p>\n<div id=\"paywall\"><\/div>\n<p class=\"ft-text\">Para la exposici\u00f3n <em>Nacimientos y Belenes Tradicionales Mallorquines<\/em>, <strong>Pilar y Carolina V\u00e1zquez han necesitado cuatro d\u00edas para colocar sus m\u00e1s de 1.100 pesebres<\/strong>, procedentes de 59 pa\u00edses y de 30 provincias espa\u00f1olas. Disfruto de sacar los belenes, pero tambi\u00e9n de guardarlos\u00bb, explica Pilar, la coleccionista de las dos hermanas y actual presidenta de la <strong>Agrupaci\u00f3 de Betlemistes Francesc Rossell\u00f3Este Jai de Nadal ha cumplido 14 a\u00f1os y las hermanas V\u00e1zquez montan su exposici\u00f3n desde 2019, con pesebres de todo tipo: de bolillos, de palos que flotaban en el mar, otro tallado en un cirio, de piedra que imita madera&#8230;<\/strong><\/p>\n<p class=\"ft-text\"><strong>El Jai de Nadal se podr\u00e1 visitar gratuitamente hasta el 3 de enero,<\/strong> a excepci\u00f3n de l<strong>a muestra de reposter\u00eda que finalizar\u00e1 el 23 de diciembre<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una cita ya consolidada de la Navidad en Palma es el Jai de Nadal organizado por el Centro de Historia y Cultura Militar de Baleares, situado en la calle Sant [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":18946,"template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[150],"class_list":["post-18950","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-exposiciones","cat_exposiciones"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jai de Nadal en Palma: un millar de belenes navide\u00f1os<\/title>\n<meta name=\"description\" content=\"Descubre Jai de Nadal en Palma, con m\u00e1s de un millar de belenes, dulces y artesan\u00eda navide\u00f1a en exposiciones tradicionales por toda la ciudad.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/visitpalma.com\/es\/event\/jai-de-nadal-exposicion-de-nacimientos-y-belenes-tradicionales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jai de Nadal en Palma: un millar de belenes navide\u00f1os\" \/>\n<meta property=\"og:description\" content=\"Descubre Jai de Nadal en Palma, con m\u00e1s de un millar de belenes, dulces y artesan\u00eda navide\u00f1a en exposiciones tradicionales por toda la ciudad.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/visitpalma.com\/es\/event\/jai-de-nadal-exposicion-de-nacimientos-y-belenes-tradicionales\/\" \/>\n<meta property=\"og:site_name\" content=\"Visit Palma\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/passionforpalma\" \/>\n<meta property=\"og:image\" content=\"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/12\/JaiDeNadal.jpg.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"357\" \/>\n\t<meta property=\"og:image:height\" content=\"501\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@passionforpalma\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/event\\\/jai-de-nadal-exposicion-de-nacimientos-y-belenes-tradicionales\\\/\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/event\\\/jai-de-nadal-exposicion-de-nacimientos-y-belenes-tradicionales\\\/\",\"name\":\"Jai de Nadal en Palma: un millar de belenes navide\u00f1os\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/event\\\/jai-de-nadal-exposicion-de-nacimientos-y-belenes-tradicionales\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/event\\\/jai-de-nadal-exposicion-de-nacimientos-y-belenes-tradicionales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/JaiDeNadal.jpg.webp\",\"datePublished\":\"2025-12-11T10:01:20+00:00\",\"description\":\"Descubre Jai de Nadal en Palma, con m\u00e1s de un millar de belenes, dulces y artesan\u00eda navide\u00f1a en exposiciones tradicionales por toda la ciudad.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/event\\\/jai-de-nadal-exposicion-de-nacimientos-y-belenes-tradicionales\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/visitpalma.com\\\/es\\\/event\\\/jai-de-nadal-exposicion-de-nacimientos-y-belenes-tradicionales\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/event\\\/jai-de-nadal-exposicion-de-nacimientos-y-belenes-tradicionales\\\/#primaryimage\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/JaiDeNadal.jpg.webp\",\"contentUrl\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/JaiDeNadal.jpg.webp\",\"width\":357,\"height\":501,\"caption\":\"Muestra de Reposteria y Belenes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/event\\\/jai-de-nadal-exposicion-de-nacimientos-y-belenes-tradicionales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventos\",\"item\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Jai de Nadal: Exposici\u00f3n de Nacimientos y Belenes Tradicionales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/\",\"name\":\"Visit Palma\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3n Turismo Palma de Mallorca 365\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Logo-Passion-for-Palma-de-Mallorca.svg\",\"contentUrl\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Logo-Passion-for-Palma-de-Mallorca.svg\",\"width\":377,\"height\":377,\"caption\":\"Fundaci\u00f3n Turismo Palma de Mallorca 365\"},\"image\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/passionforpalma\",\"https:\\\/\\\/x.com\\\/passionforpalma\",\"https:\\\/\\\/www.instagram.com\\\/passionforpalma_\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCALF2N1FRnmAZYBttkQjedA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jai de Nadal en Palma: un millar de belenes navide\u00f1os","description":"Descubre Jai de Nadal en Palma, con m\u00e1s de un millar de belenes, dulces y artesan\u00eda navide\u00f1a en exposiciones tradicionales por toda la ciudad.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/visitpalma.com\/es\/event\/jai-de-nadal-exposicion-de-nacimientos-y-belenes-tradicionales\/","og_locale":"es_ES","og_type":"article","og_title":"Jai de Nadal en Palma: un millar de belenes navide\u00f1os","og_description":"Descubre Jai de Nadal en Palma, con m\u00e1s de un millar de belenes, dulces y artesan\u00eda navide\u00f1a en exposiciones tradicionales por toda la ciudad.","og_url":"https:\/\/visitpalma.com\/es\/event\/jai-de-nadal-exposicion-de-nacimientos-y-belenes-tradicionales\/","og_site_name":"Visit Palma","article_publisher":"https:\/\/www.facebook.com\/passionforpalma","og_image":[{"width":357,"height":501,"url":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/12\/JaiDeNadal.jpg.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_site":"@passionforpalma","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/visitpalma.com\/es\/event\/jai-de-nadal-exposicion-de-nacimientos-y-belenes-tradicionales\/","url":"https:\/\/visitpalma.com\/es\/event\/jai-de-nadal-exposicion-de-nacimientos-y-belenes-tradicionales\/","name":"Jai de Nadal en Palma: un millar de belenes navide\u00f1os","isPartOf":{"@id":"https:\/\/visitpalma.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/visitpalma.com\/es\/event\/jai-de-nadal-exposicion-de-nacimientos-y-belenes-tradicionales\/#primaryimage"},"image":{"@id":"https:\/\/visitpalma.com\/es\/event\/jai-de-nadal-exposicion-de-nacimientos-y-belenes-tradicionales\/#primaryimage"},"thumbnailUrl":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/12\/JaiDeNadal.jpg.webp","datePublished":"2025-12-11T10:01:20+00:00","description":"Descubre Jai de Nadal en Palma, con m\u00e1s de un millar de belenes, dulces y artesan\u00eda navide\u00f1a en exposiciones tradicionales por toda la ciudad.","breadcrumb":{"@id":"https:\/\/visitpalma.com\/es\/event\/jai-de-nadal-exposicion-de-nacimientos-y-belenes-tradicionales\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/visitpalma.com\/es\/event\/jai-de-nadal-exposicion-de-nacimientos-y-belenes-tradicionales\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/visitpalma.com\/es\/event\/jai-de-nadal-exposicion-de-nacimientos-y-belenes-tradicionales\/#primaryimage","url":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/12\/JaiDeNadal.jpg.webp","contentUrl":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/12\/JaiDeNadal.jpg.webp","width":357,"height":501,"caption":"Muestra de Reposteria y Belenes"},{"@type":"BreadcrumbList","@id":"https:\/\/visitpalma.com\/es\/event\/jai-de-nadal-exposicion-de-nacimientos-y-belenes-tradicionales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/visitpalma.com\/es\/"},{"@type":"ListItem","position":2,"name":"Eventos","item":"https:\/\/visitpalma.com\/es\/events\/"},{"@type":"ListItem","position":3,"name":"Jai de Nadal: Exposici\u00f3n de Nacimientos y Belenes Tradicionales"}]},{"@type":"WebSite","@id":"https:\/\/visitpalma.com\/es\/#website","url":"https:\/\/visitpalma.com\/es\/","name":"Visit Palma","description":"","publisher":{"@id":"https:\/\/visitpalma.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/visitpalma.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/visitpalma.com\/es\/#organization","name":"Fundaci\u00f3n Turismo Palma de Mallorca 365","url":"https:\/\/visitpalma.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/visitpalma.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/05\/Logo-Passion-for-Palma-de-Mallorca.svg","contentUrl":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/05\/Logo-Passion-for-Palma-de-Mallorca.svg","width":377,"height":377,"caption":"Fundaci\u00f3n Turismo Palma de Mallorca 365"},"image":{"@id":"https:\/\/visitpalma.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/passionforpalma","https:\/\/x.com\/passionforpalma","https:\/\/www.instagram.com\/passionforpalma_\/","https:\/\/www.youtube.com\/channel\/UCALF2N1FRnmAZYBttkQjedA"]}]}},"_links":{"self":[{"href":"https:\/\/visitpalma.com\/es\/wp-json\/wp\/v2\/tribe_events\/18950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visitpalma.com\/es\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/visitpalma.com\/es\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/visitpalma.com\/es\/wp-json\/wp\/v2\/users\/4"}],"version-history":[{"count":1,"href":"https:\/\/visitpalma.com\/es\/wp-json\/wp\/v2\/tribe_events\/18950\/revisions"}],"predecessor-version":[{"id":18951,"href":"https:\/\/visitpalma.com\/es\/wp-json\/wp\/v2\/tribe_events\/18950\/revisions\/18951"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visitpalma.com\/es\/wp-json\/wp\/v2\/media\/18946"}],"wp:attachment":[{"href":"https:\/\/visitpalma.com\/es\/wp-json\/wp\/v2\/media?parent=18950"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visitpalma.com\/es\/wp-json\/wp\/v2\/tags?post=18950"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/visitpalma.com\/es\/wp-json\/wp\/v2\/tribe_events_cat?post=18950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}