{"id":18239,"date":"2025-10-28T12:03:25","date_gmt":"2025-10-28T11:03:25","guid":{"rendered":"https:\/\/visitpalma.com\/?post_type=tribe_events&#038;p=18239"},"modified":"2025-10-28T12:03:25","modified_gmt":"2025-10-28T11:03:25","slug":"mostres-de-ball-de-bot-i-ballades-populars","status":"publish","type":"tribe_events","link":"https:\/\/visitpalma.com\/es\/event\/mostres-de-ball-de-bot-i-ballades-populars\/","title":{"rendered":"Mostres de Ball de Bot i Ballades Populars"},"content":{"rendered":"<p class=\"gt-block\">Palma celebra la riqueza de la danza y los trajes tradicionales de Mallorca durante todo noviembre con la\u00a0<strong>\u201cMostres de Ball de Bot i Baladas Populares\u201d<\/strong>\u00a0\u2013 una serie de espect\u00e1culos al aire libre que muestran la vitalidad del folclore mallorqu\u00edn.<\/p>\n<p class=\"gt-block\">Organizados en colaboraci\u00f3n con grupos folcl\u00f3ricos locales, estos eventos honran el patrimonio cultural de la isla a trav\u00e9s de presentaciones en vivo de\u00a0<em>bola de bot<\/em>, m\u00fasica tradicional y trajes regionales bellamente conservados: verdaderos s\u00edmbolos de la identidad mallorquina y del esp\u00edritu mediterr\u00e1neo.<\/p>\n<p class=\"gt-block\">Cada evento concluye con una\u00a0<strong>baile comunitario abierto<\/strong>, invitando a todos a sumarse y experimentar de primera mano la alegr\u00eda de estos ritmos centenarios.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Palma celebra la riqueza de la danza y los trajes tradicionales de Mallorca durante todo noviembre con la\u00a0\u201cMostres de Ball de Bot i Baladas Populares\u201d\u00a0\u2013 una serie de espect\u00e1culos al [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":18240,"template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[51],"class_list":["post-18239","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-musica-danza","cat_musica-danza"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mostres de Ball de Bot Palma 2025 \u2013 Cultura y tradici\u00f3n<\/title>\n<meta name=\"description\" content=\"Disfruta del folklore mallorqu\u00edn en Palma con las Mostres de Ball de Bot del 2 al 30 de noviembre. Exhibiciones y bailes abiertos gratuitos en distintos puntos de la ciudad.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/visitpalma.com\/es\/event\/mostres-de-ball-de-bot-i-ballades-populars\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mostres de Ball de Bot Palma 2025 \u2013 Cultura y tradici\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Disfruta del folklore mallorqu\u00edn en Palma con las Mostres de Ball de Bot del 2 al 30 de noviembre. Exhibiciones y bailes abiertos gratuitos en distintos puntos de la ciudad.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/visitpalma.com\/es\/event\/mostres-de-ball-de-bot-i-ballades-populars\/\" \/>\n<meta property=\"og:site_name\" content=\"Visit Palma\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/passionforpalma\" \/>\n<meta property=\"og:image\" content=\"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/10\/F12674-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"453\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@passionforpalma\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/event\\\/mostres-de-ball-de-bot-i-ballades-populars\\\/\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/event\\\/mostres-de-ball-de-bot-i-ballades-populars\\\/\",\"name\":\"Mostres de Ball de Bot Palma 2025 \u2013 Cultura y tradici\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/event\\\/mostres-de-ball-de-bot-i-ballades-populars\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/event\\\/mostres-de-ball-de-bot-i-ballades-populars\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/F12674-2.jpg\",\"datePublished\":\"2025-10-28T11:03:25+00:00\",\"description\":\"Disfruta del folklore mallorqu\u00edn en Palma con las Mostres de Ball de Bot del 2 al 30 de noviembre. Exhibiciones y bailes abiertos gratuitos en distintos puntos de la ciudad.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/event\\\/mostres-de-ball-de-bot-i-ballades-populars\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/visitpalma.com\\\/es\\\/event\\\/mostres-de-ball-de-bot-i-ballades-populars\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/event\\\/mostres-de-ball-de-bot-i-ballades-populars\\\/#primaryimage\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/F12674-2.jpg\",\"contentUrl\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/F12674-2.jpg\",\"width\":453,\"height\":640,\"caption\":\"Mostres de Ball de Bot\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/event\\\/mostres-de-ball-de-bot-i-ballades-populars\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventos\",\"item\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mostres de Ball de Bot i Ballades Populars\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/\",\"name\":\"Visit Palma\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3n Turismo Palma de Mallorca 365\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Logo-Passion-for-Palma-de-Mallorca.svg\",\"contentUrl\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Logo-Passion-for-Palma-de-Mallorca.svg\",\"width\":377,\"height\":377,\"caption\":\"Fundaci\u00f3n Turismo Palma de Mallorca 365\"},\"image\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/passionforpalma\",\"https:\\\/\\\/x.com\\\/passionforpalma\",\"https:\\\/\\\/www.instagram.com\\\/passionforpalma_\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCALF2N1FRnmAZYBttkQjedA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mostres de Ball de Bot Palma 2025 \u2013 Cultura y tradici\u00f3n","description":"Disfruta del folklore mallorqu\u00edn en Palma con las Mostres de Ball de Bot del 2 al 30 de noviembre. Exhibiciones y bailes abiertos gratuitos en distintos puntos de la ciudad.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/visitpalma.com\/es\/event\/mostres-de-ball-de-bot-i-ballades-populars\/","og_locale":"es_ES","og_type":"article","og_title":"Mostres de Ball de Bot Palma 2025 \u2013 Cultura y tradici\u00f3n","og_description":"Disfruta del folklore mallorqu\u00edn en Palma con las Mostres de Ball de Bot del 2 al 30 de noviembre. Exhibiciones y bailes abiertos gratuitos en distintos puntos de la ciudad.","og_url":"https:\/\/visitpalma.com\/es\/event\/mostres-de-ball-de-bot-i-ballades-populars\/","og_site_name":"Visit Palma","article_publisher":"https:\/\/www.facebook.com\/passionforpalma","og_image":[{"width":453,"height":640,"url":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/10\/F12674-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@passionforpalma","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/visitpalma.com\/es\/event\/mostres-de-ball-de-bot-i-ballades-populars\/","url":"https:\/\/visitpalma.com\/es\/event\/mostres-de-ball-de-bot-i-ballades-populars\/","name":"Mostres de Ball de Bot Palma 2025 \u2013 Cultura y tradici\u00f3n","isPartOf":{"@id":"https:\/\/visitpalma.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/visitpalma.com\/es\/event\/mostres-de-ball-de-bot-i-ballades-populars\/#primaryimage"},"image":{"@id":"https:\/\/visitpalma.com\/es\/event\/mostres-de-ball-de-bot-i-ballades-populars\/#primaryimage"},"thumbnailUrl":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/10\/F12674-2.jpg","datePublished":"2025-10-28T11:03:25+00:00","description":"Disfruta del folklore mallorqu\u00edn en Palma con las Mostres de Ball de Bot del 2 al 30 de noviembre. Exhibiciones y bailes abiertos gratuitos en distintos puntos de la ciudad.","breadcrumb":{"@id":"https:\/\/visitpalma.com\/es\/event\/mostres-de-ball-de-bot-i-ballades-populars\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/visitpalma.com\/es\/event\/mostres-de-ball-de-bot-i-ballades-populars\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/visitpalma.com\/es\/event\/mostres-de-ball-de-bot-i-ballades-populars\/#primaryimage","url":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/10\/F12674-2.jpg","contentUrl":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/10\/F12674-2.jpg","width":453,"height":640,"caption":"Mostres de Ball de Bot"},{"@type":"BreadcrumbList","@id":"https:\/\/visitpalma.com\/es\/event\/mostres-de-ball-de-bot-i-ballades-populars\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/visitpalma.com\/es\/"},{"@type":"ListItem","position":2,"name":"Eventos","item":"https:\/\/visitpalma.com\/es\/events\/"},{"@type":"ListItem","position":3,"name":"Mostres de Ball de Bot i Ballades Populars"}]},{"@type":"WebSite","@id":"https:\/\/visitpalma.com\/es\/#website","url":"https:\/\/visitpalma.com\/es\/","name":"Visit Palma","description":"","publisher":{"@id":"https:\/\/visitpalma.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/visitpalma.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/visitpalma.com\/es\/#organization","name":"Fundaci\u00f3n Turismo Palma de Mallorca 365","url":"https:\/\/visitpalma.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/visitpalma.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/05\/Logo-Passion-for-Palma-de-Mallorca.svg","contentUrl":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/05\/Logo-Passion-for-Palma-de-Mallorca.svg","width":377,"height":377,"caption":"Fundaci\u00f3n Turismo Palma de Mallorca 365"},"image":{"@id":"https:\/\/visitpalma.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/passionforpalma","https:\/\/x.com\/passionforpalma","https:\/\/www.instagram.com\/passionforpalma_\/","https:\/\/www.youtube.com\/channel\/UCALF2N1FRnmAZYBttkQjedA"]}]}},"_links":{"self":[{"href":"https:\/\/visitpalma.com\/es\/wp-json\/wp\/v2\/tribe_events\/18239","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visitpalma.com\/es\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/visitpalma.com\/es\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/visitpalma.com\/es\/wp-json\/wp\/v2\/users\/4"}],"version-history":[{"count":1,"href":"https:\/\/visitpalma.com\/es\/wp-json\/wp\/v2\/tribe_events\/18239\/revisions"}],"predecessor-version":[{"id":18241,"href":"https:\/\/visitpalma.com\/es\/wp-json\/wp\/v2\/tribe_events\/18239\/revisions\/18241"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visitpalma.com\/es\/wp-json\/wp\/v2\/media\/18240"}],"wp:attachment":[{"href":"https:\/\/visitpalma.com\/es\/wp-json\/wp\/v2\/media?parent=18239"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visitpalma.com\/es\/wp-json\/wp\/v2\/tags?post=18239"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/visitpalma.com\/es\/wp-json\/wp\/v2\/tribe_events_cat?post=18239"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}