{"id":16588,"date":"2025-09-22T10:24:43","date_gmt":"2025-09-22T08:24:43","guid":{"rendered":"https:\/\/visitpalma.com\/?post_type=tribe_events&#038;p=16588"},"modified":"2025-09-22T10:24:43","modified_gmt":"2025-09-22T08:24:43","slug":"pelayo-varela-the-artist-is-dead-long-live-ai","status":"publish","type":"tribe_events","link":"https:\/\/visitpalma.com\/es\/event\/pelayo-varela-the-artist-is-dead-long-live-ai\/","title":{"rendered":"Pelayo Varela \u2013 \u201cThe artist is dead, long live AI\u201d"},"content":{"rendered":"<p>Del <strong data-start=\"185\" data-end=\"236\">20 de septiembre de 2025 al 11 de enero de 2026<\/strong>, Casal Solleric acoge <em data-start=\"259\" data-end=\"311\">Pelayo Varela \u2013 \u201cThe artist is dead, long live AI\u201d<\/em>, una exposici\u00f3n comisariada por Avelino Sala que mezcla obras recientes con piezas de nueva producci\u00f3n. Varela plantea preguntas profundas: \u00bfcu\u00e1l es el rol del artista hoy?, \u00bfqu\u00e9 sentido tiene la autor\u00eda?, y c\u00f3mo influye la inteligencia artificial en el futuro del arte? Con entradas gratuitas, esta muestra invita a un recorrido reflexivo entre biograf\u00eda, identidad, producci\u00f3n creativa y tecnolog\u00eda art\u00edstica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Del 20 de septiembre de 2025 al 11 de enero de 2026, Casal Solleric acoge Pelayo Varela \u2013 \u201cThe artist is dead, long live AI\u201d, una exposici\u00f3n comisariada por Avelino [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":16589,"template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[150],"class_list":["post-16588","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-exposiciones","cat_exposiciones"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pelayo Varela \u201cThe artist is dead, long live AI\u201d | Palma 2025<\/title>\n<meta name=\"description\" content=\"Descubre la exposici\u00f3n de Pelayo Varela en Casal Solleric, Palma. Arte, autor\u00eda e inteligencia artificial del 20\/09\/25 al 11\/01\/26.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/visitpalma.com\/es\/event\/pelayo-varela-the-artist-is-dead-long-live-ai\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pelayo Varela \u201cThe artist is dead, long live AI\u201d | Palma 2025\" \/>\n<meta property=\"og:description\" content=\"Descubre la exposici\u00f3n de Pelayo Varela en Casal Solleric, Palma. Arte, autor\u00eda e inteligencia artificial del 20\/09\/25 al 11\/01\/26.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/visitpalma.com\/es\/event\/pelayo-varela-the-artist-is-dead-long-live-ai\/\" \/>\n<meta property=\"og:site_name\" content=\"Visit Palma\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/passionforpalma\" \/>\n<meta property=\"og:image\" content=\"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/09\/Pelayo-Varela-Palma-2025.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"812\" \/>\n\t<meta property=\"og:image:height\" content=\"812\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@passionforpalma\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/event\\\/pelayo-varela-the-artist-is-dead-long-live-ai\\\/\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/event\\\/pelayo-varela-the-artist-is-dead-long-live-ai\\\/\",\"name\":\"Pelayo Varela \u201cThe artist is dead, long live AI\u201d | Palma 2025\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/event\\\/pelayo-varela-the-artist-is-dead-long-live-ai\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/event\\\/pelayo-varela-the-artist-is-dead-long-live-ai\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Pelayo-Varela-Palma-2025.jpg\",\"datePublished\":\"2025-09-22T08:24:43+00:00\",\"description\":\"Descubre la exposici\u00f3n de Pelayo Varela en Casal Solleric, Palma. Arte, autor\u00eda e inteligencia artificial del 20\\\/09\\\/25 al 11\\\/01\\\/26.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/event\\\/pelayo-varela-the-artist-is-dead-long-live-ai\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/visitpalma.com\\\/es\\\/event\\\/pelayo-varela-the-artist-is-dead-long-live-ai\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/event\\\/pelayo-varela-the-artist-is-dead-long-live-ai\\\/#primaryimage\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Pelayo-Varela-Palma-2025.jpg\",\"contentUrl\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Pelayo-Varela-Palma-2025.jpg\",\"width\":812,\"height\":812,\"caption\":\"Pelayo Varela Palma 2025\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/event\\\/pelayo-varela-the-artist-is-dead-long-live-ai\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventos\",\"item\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pelayo Varela \u2013 \u201cThe artist is dead, long live AI\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/\",\"name\":\"Visit Palma\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3n Turismo Palma de Mallorca 365\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Logo-Passion-for-Palma-de-Mallorca.svg\",\"contentUrl\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Logo-Passion-for-Palma-de-Mallorca.svg\",\"width\":377,\"height\":377,\"caption\":\"Fundaci\u00f3n Turismo Palma de Mallorca 365\"},\"image\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/passionforpalma\",\"https:\\\/\\\/x.com\\\/passionforpalma\",\"https:\\\/\\\/www.instagram.com\\\/passionforpalma_\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCALF2N1FRnmAZYBttkQjedA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pelayo Varela \u201cThe artist is dead, long live AI\u201d | Palma 2025","description":"Descubre la exposici\u00f3n de Pelayo Varela en Casal Solleric, Palma. Arte, autor\u00eda e inteligencia artificial del 20\/09\/25 al 11\/01\/26.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/visitpalma.com\/es\/event\/pelayo-varela-the-artist-is-dead-long-live-ai\/","og_locale":"es_ES","og_type":"article","og_title":"Pelayo Varela \u201cThe artist is dead, long live AI\u201d | Palma 2025","og_description":"Descubre la exposici\u00f3n de Pelayo Varela en Casal Solleric, Palma. Arte, autor\u00eda e inteligencia artificial del 20\/09\/25 al 11\/01\/26.","og_url":"https:\/\/visitpalma.com\/es\/event\/pelayo-varela-the-artist-is-dead-long-live-ai\/","og_site_name":"Visit Palma","article_publisher":"https:\/\/www.facebook.com\/passionforpalma","og_image":[{"width":812,"height":812,"url":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/09\/Pelayo-Varela-Palma-2025.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@passionforpalma","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/visitpalma.com\/es\/event\/pelayo-varela-the-artist-is-dead-long-live-ai\/","url":"https:\/\/visitpalma.com\/es\/event\/pelayo-varela-the-artist-is-dead-long-live-ai\/","name":"Pelayo Varela \u201cThe artist is dead, long live AI\u201d | Palma 2025","isPartOf":{"@id":"https:\/\/visitpalma.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/visitpalma.com\/es\/event\/pelayo-varela-the-artist-is-dead-long-live-ai\/#primaryimage"},"image":{"@id":"https:\/\/visitpalma.com\/es\/event\/pelayo-varela-the-artist-is-dead-long-live-ai\/#primaryimage"},"thumbnailUrl":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/09\/Pelayo-Varela-Palma-2025.jpg","datePublished":"2025-09-22T08:24:43+00:00","description":"Descubre la exposici\u00f3n de Pelayo Varela en Casal Solleric, Palma. Arte, autor\u00eda e inteligencia artificial del 20\/09\/25 al 11\/01\/26.","breadcrumb":{"@id":"https:\/\/visitpalma.com\/es\/event\/pelayo-varela-the-artist-is-dead-long-live-ai\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/visitpalma.com\/es\/event\/pelayo-varela-the-artist-is-dead-long-live-ai\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/visitpalma.com\/es\/event\/pelayo-varela-the-artist-is-dead-long-live-ai\/#primaryimage","url":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/09\/Pelayo-Varela-Palma-2025.jpg","contentUrl":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/09\/Pelayo-Varela-Palma-2025.jpg","width":812,"height":812,"caption":"Pelayo Varela Palma 2025"},{"@type":"BreadcrumbList","@id":"https:\/\/visitpalma.com\/es\/event\/pelayo-varela-the-artist-is-dead-long-live-ai\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/visitpalma.com\/es\/"},{"@type":"ListItem","position":2,"name":"Eventos","item":"https:\/\/visitpalma.com\/es\/events\/"},{"@type":"ListItem","position":3,"name":"Pelayo Varela \u2013 \u201cThe artist is dead, long live AI\u201d"}]},{"@type":"WebSite","@id":"https:\/\/visitpalma.com\/es\/#website","url":"https:\/\/visitpalma.com\/es\/","name":"Visit Palma","description":"","publisher":{"@id":"https:\/\/visitpalma.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/visitpalma.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/visitpalma.com\/es\/#organization","name":"Fundaci\u00f3n Turismo Palma de Mallorca 365","url":"https:\/\/visitpalma.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/visitpalma.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/05\/Logo-Passion-for-Palma-de-Mallorca.svg","contentUrl":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/05\/Logo-Passion-for-Palma-de-Mallorca.svg","width":377,"height":377,"caption":"Fundaci\u00f3n Turismo Palma de Mallorca 365"},"image":{"@id":"https:\/\/visitpalma.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/passionforpalma","https:\/\/x.com\/passionforpalma","https:\/\/www.instagram.com\/passionforpalma_\/","https:\/\/www.youtube.com\/channel\/UCALF2N1FRnmAZYBttkQjedA"]}]}},"_links":{"self":[{"href":"https:\/\/visitpalma.com\/es\/wp-json\/wp\/v2\/tribe_events\/16588","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visitpalma.com\/es\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/visitpalma.com\/es\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/visitpalma.com\/es\/wp-json\/wp\/v2\/users\/4"}],"version-history":[{"count":1,"href":"https:\/\/visitpalma.com\/es\/wp-json\/wp\/v2\/tribe_events\/16588\/revisions"}],"predecessor-version":[{"id":16593,"href":"https:\/\/visitpalma.com\/es\/wp-json\/wp\/v2\/tribe_events\/16588\/revisions\/16593"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visitpalma.com\/es\/wp-json\/wp\/v2\/media\/16589"}],"wp:attachment":[{"href":"https:\/\/visitpalma.com\/es\/wp-json\/wp\/v2\/media?parent=16588"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visitpalma.com\/es\/wp-json\/wp\/v2\/tags?post=16588"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/visitpalma.com\/es\/wp-json\/wp\/v2\/tribe_events_cat?post=16588"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}