{"id":16141,"date":"2025-09-08T10:19:09","date_gmt":"2025-09-08T08:19:09","guid":{"rendered":"https:\/\/visitpalma.com\/?post_type=tribe_events&#038;p=16141"},"modified":"2025-09-08T10:19:09","modified_gmt":"2025-09-08T08:19:09","slug":"colonya-palma-muntanya-film-festival","status":"publish","type":"tribe_events","link":"https:\/\/visitpalma.com\/es\/event\/colonya-palma-muntanya-film-festival\/","title":{"rendered":"Colonya Palma Muntanya Film Festival"},"content":{"rendered":"<p data-start=\"213\" data-end=\"515\">El <strong data-start=\"216\" data-end=\"256\">Colonya Palma Muntanya Film Festival<\/strong> celebra su 16.\u00aa edici\u00f3n con una programaci\u00f3n dedicada al cine documental de monta\u00f1a, tanto internacional como producido en las Islas Baleares. El festival incluye pel\u00edculas, cortometrajes, documentos f\u00edlmicos y fotogr\u00e1ficos de valor hist\u00f3rico y documental.<\/p>\n<p data-start=\"517\" data-end=\"822\">Adem\u00e1s, la programaci\u00f3n se complementa con presentaciones de libros de monta\u00f1a, exposiciones de fotograf\u00eda, conciertos y proyecciones audiovisuales. Participan realizadores, productores de cine de monta\u00f1a y naturaleza, alpinistas, escaladores y numerosos aficionados al cine, la fotograf\u00eda y la monta\u00f1a.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Colonya Palma Muntanya Film Festival celebra su 16.\u00aa edici\u00f3n con una programaci\u00f3n dedicada al cine documental de monta\u00f1a, tanto internacional como producido en las Islas Baleares. El festival incluye [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":16142,"template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[154],"class_list":["post-16141","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-otros-eventos","cat_otros-eventos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Colonya Palma Muntanya Film Festival 16.\u00aa edici\u00f3n<\/title>\n<meta name=\"description\" content=\"Descubre la 16.\u00aa edici\u00f3n del Colonya Palma Muntanya Film Festival: cine documental de monta\u00f1a, exposiciones, libros y conciertos en Baleares.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/visitpalma.com\/es\/event\/colonya-palma-muntanya-film-festival\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Colonya Palma Muntanya Film Festival 16.\u00aa edici\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Descubre la 16.\u00aa edici\u00f3n del Colonya Palma Muntanya Film Festival: cine documental de monta\u00f1a, exposiciones, libros y conciertos en Baleares.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/visitpalma.com\/es\/event\/colonya-palma-muntanya-film-festival\/\" \/>\n<meta property=\"og:site_name\" content=\"Visit Palma\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/passionforpalma\" \/>\n<meta property=\"og:image\" content=\"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/09\/Colonya-Palma-Muntanya-Film-Festival.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1140\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@passionforpalma\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/event\\\/colonya-palma-muntanya-film-festival\\\/\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/event\\\/colonya-palma-muntanya-film-festival\\\/\",\"name\":\"Colonya Palma Muntanya Film Festival 16.\u00aa edici\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/event\\\/colonya-palma-muntanya-film-festival\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/event\\\/colonya-palma-muntanya-film-festival\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Colonya-Palma-Muntanya-Film-Festival.jpg\",\"datePublished\":\"2025-09-08T08:19:09+00:00\",\"description\":\"Descubre la 16.\u00aa edici\u00f3n del Colonya Palma Muntanya Film Festival: cine documental de monta\u00f1a, exposiciones, libros y conciertos en Baleares.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/event\\\/colonya-palma-muntanya-film-festival\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/visitpalma.com\\\/es\\\/event\\\/colonya-palma-muntanya-film-festival\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/event\\\/colonya-palma-muntanya-film-festival\\\/#primaryimage\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Colonya-Palma-Muntanya-Film-Festival.jpg\",\"contentUrl\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Colonya-Palma-Muntanya-Film-Festival.jpg\",\"width\":1140,\"height\":600,\"caption\":\"Colonya Palma Muntanya Film Festival\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/event\\\/colonya-palma-muntanya-film-festival\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventos\",\"item\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Colonya Palma Muntanya Film Festival\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/\",\"name\":\"Visit Palma\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3n Turismo Palma de Mallorca 365\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Logo-Passion-for-Palma-de-Mallorca.svg\",\"contentUrl\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Logo-Passion-for-Palma-de-Mallorca.svg\",\"width\":377,\"height\":377,\"caption\":\"Fundaci\u00f3n Turismo Palma de Mallorca 365\"},\"image\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/passionforpalma\",\"https:\\\/\\\/x.com\\\/passionforpalma\",\"https:\\\/\\\/www.instagram.com\\\/passionforpalma_\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCALF2N1FRnmAZYBttkQjedA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Colonya Palma Muntanya Film Festival 16.\u00aa edici\u00f3n","description":"Descubre la 16.\u00aa edici\u00f3n del Colonya Palma Muntanya Film Festival: cine documental de monta\u00f1a, exposiciones, libros y conciertos en Baleares.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/visitpalma.com\/es\/event\/colonya-palma-muntanya-film-festival\/","og_locale":"es_ES","og_type":"article","og_title":"Colonya Palma Muntanya Film Festival 16.\u00aa edici\u00f3n","og_description":"Descubre la 16.\u00aa edici\u00f3n del Colonya Palma Muntanya Film Festival: cine documental de monta\u00f1a, exposiciones, libros y conciertos en Baleares.","og_url":"https:\/\/visitpalma.com\/es\/event\/colonya-palma-muntanya-film-festival\/","og_site_name":"Visit Palma","article_publisher":"https:\/\/www.facebook.com\/passionforpalma","og_image":[{"width":1140,"height":600,"url":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/09\/Colonya-Palma-Muntanya-Film-Festival.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@passionforpalma","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/visitpalma.com\/es\/event\/colonya-palma-muntanya-film-festival\/","url":"https:\/\/visitpalma.com\/es\/event\/colonya-palma-muntanya-film-festival\/","name":"Colonya Palma Muntanya Film Festival 16.\u00aa edici\u00f3n","isPartOf":{"@id":"https:\/\/visitpalma.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/visitpalma.com\/es\/event\/colonya-palma-muntanya-film-festival\/#primaryimage"},"image":{"@id":"https:\/\/visitpalma.com\/es\/event\/colonya-palma-muntanya-film-festival\/#primaryimage"},"thumbnailUrl":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/09\/Colonya-Palma-Muntanya-Film-Festival.jpg","datePublished":"2025-09-08T08:19:09+00:00","description":"Descubre la 16.\u00aa edici\u00f3n del Colonya Palma Muntanya Film Festival: cine documental de monta\u00f1a, exposiciones, libros y conciertos en Baleares.","breadcrumb":{"@id":"https:\/\/visitpalma.com\/es\/event\/colonya-palma-muntanya-film-festival\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/visitpalma.com\/es\/event\/colonya-palma-muntanya-film-festival\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/visitpalma.com\/es\/event\/colonya-palma-muntanya-film-festival\/#primaryimage","url":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/09\/Colonya-Palma-Muntanya-Film-Festival.jpg","contentUrl":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/09\/Colonya-Palma-Muntanya-Film-Festival.jpg","width":1140,"height":600,"caption":"Colonya Palma Muntanya Film Festival"},{"@type":"BreadcrumbList","@id":"https:\/\/visitpalma.com\/es\/event\/colonya-palma-muntanya-film-festival\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/visitpalma.com\/es\/"},{"@type":"ListItem","position":2,"name":"Eventos","item":"https:\/\/visitpalma.com\/es\/events\/"},{"@type":"ListItem","position":3,"name":"Colonya Palma Muntanya Film Festival"}]},{"@type":"WebSite","@id":"https:\/\/visitpalma.com\/es\/#website","url":"https:\/\/visitpalma.com\/es\/","name":"Visit Palma","description":"","publisher":{"@id":"https:\/\/visitpalma.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/visitpalma.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/visitpalma.com\/es\/#organization","name":"Fundaci\u00f3n Turismo Palma de Mallorca 365","url":"https:\/\/visitpalma.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/visitpalma.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/05\/Logo-Passion-for-Palma-de-Mallorca.svg","contentUrl":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/05\/Logo-Passion-for-Palma-de-Mallorca.svg","width":377,"height":377,"caption":"Fundaci\u00f3n Turismo Palma de Mallorca 365"},"image":{"@id":"https:\/\/visitpalma.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/passionforpalma","https:\/\/x.com\/passionforpalma","https:\/\/www.instagram.com\/passionforpalma_\/","https:\/\/www.youtube.com\/channel\/UCALF2N1FRnmAZYBttkQjedA"]}]}},"_links":{"self":[{"href":"https:\/\/visitpalma.com\/es\/wp-json\/wp\/v2\/tribe_events\/16141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visitpalma.com\/es\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/visitpalma.com\/es\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/visitpalma.com\/es\/wp-json\/wp\/v2\/users\/4"}],"version-history":[{"count":1,"href":"https:\/\/visitpalma.com\/es\/wp-json\/wp\/v2\/tribe_events\/16141\/revisions"}],"predecessor-version":[{"id":16146,"href":"https:\/\/visitpalma.com\/es\/wp-json\/wp\/v2\/tribe_events\/16141\/revisions\/16146"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visitpalma.com\/es\/wp-json\/wp\/v2\/media\/16142"}],"wp:attachment":[{"href":"https:\/\/visitpalma.com\/es\/wp-json\/wp\/v2\/media?parent=16141"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visitpalma.com\/es\/wp-json\/wp\/v2\/tags?post=16141"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/visitpalma.com\/es\/wp-json\/wp\/v2\/tribe_events_cat?post=16141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}