{"id":15466,"date":"2025-07-25T11:56:08","date_gmt":"2025-07-25T09:56:08","guid":{"rendered":"https:\/\/visitpalma.com\/?post_type=tribe_events&#038;p=15466"},"modified":"2025-07-25T11:56:08","modified_gmt":"2025-07-25T09:56:08","slug":"2a-edicio-de-la-gala-de-dansa-de-ballarins-mallorquins","status":"publish","type":"tribe_events","link":"https:\/\/visitpalma.com\/es\/event\/2a-edicio-de-la-gala-de-dansa-de-ballarins-mallorquins\/","title":{"rendered":"2\u00aa edici\u00f3 de la Gala de Dansa de Ballarins Mallorquins"},"content":{"rendered":"<p data-start=\"927\" data-end=\"993\"><strong data-start=\"927\" data-end=\"993\">El talento mallorqu\u00edn brilla en la 2\u00aa Gala de Danza en Bellver<\/strong><\/p>\n<p data-start=\"995\" data-end=\"1590\">El pr\u00f3ximo 12 de agosto de 2025 a las 21\u202fh, el Castell de Bellver ser\u00e1 escenario de la 2\u00aa Gala de Danza de Bailarines Mallorquines. Tras el \u00e9xito de su primera edici\u00f3n, la gala regresa con una cuidada selecci\u00f3n de bailarines de la isla como Antoni Canyelles, Tom\u00e1s Sanza Casas, Aina Busquets, Maria del Mar Bestard y Francesca Busquets, quien tambi\u00e9n asume la direcci\u00f3n art\u00edstica. El repertorio combinar\u00e1 obras cl\u00e1sicas como <em data-start=\"1420\" data-end=\"1433\">Cisne Negro<\/em> y <em data-start=\"1436\" data-end=\"1447\">Satanella<\/em> con piezas neocl\u00e1sicas como <em data-start=\"1476\" data-end=\"1484\">Sonata<\/em> y <em data-start=\"1487\" data-end=\"1495\">Timing<\/em>.<br data-start=\"1496\" data-end=\"1499\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El talento mallorqu\u00edn brilla en la 2\u00aa Gala de Danza en Bellver El pr\u00f3ximo 12 de agosto de 2025 a las 21\u202fh, el Castell de Bellver ser\u00e1 escenario de la [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":15467,"template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[51],"class_list":["post-15466","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-musica-danza","cat_musica-danza"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>2\u00aa Gala de Dansa Ballarins Mallorquins \u2013 Bellver 12 ago 2025<\/title>\n<meta name=\"description\" content=\"Disfruta la 2\u00aa Gala de Dansa de Ballarins Mallorquins en el Castell de Bellver, 12\u202fagosto\u202f2025 a las\u202f21\u202fh. Espect\u00e1culo \u00fanico con talento local. Entradas ya a la venta.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/visitpalma.com\/es\/event\/2a-edicio-de-la-gala-de-dansa-de-ballarins-mallorquins\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"2\u00aa Gala de Dansa Ballarins Mallorquins \u2013 Bellver 12 ago 2025\" \/>\n<meta property=\"og:description\" content=\"Disfruta la 2\u00aa Gala de Dansa de Ballarins Mallorquins en el Castell de Bellver, 12\u202fagosto\u202f2025 a las\u202f21\u202fh. Espect\u00e1culo \u00fanico con talento local. Entradas ya a la venta.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/visitpalma.com\/es\/event\/2a-edicio-de-la-gala-de-dansa-de-ballarins-mallorquins\/\" \/>\n<meta property=\"og:site_name\" content=\"Visit Palma\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/passionforpalma\" \/>\n<meta property=\"og:image\" content=\"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/07\/Gala-de-Dansa-Ballarins-Mallorquins-2025-Bellver.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"315\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@passionforpalma\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/event\\\/2a-edicio-de-la-gala-de-dansa-de-ballarins-mallorquins\\\/\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/event\\\/2a-edicio-de-la-gala-de-dansa-de-ballarins-mallorquins\\\/\",\"name\":\"2\u00aa Gala de Dansa Ballarins Mallorquins \u2013 Bellver 12 ago 2025\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/event\\\/2a-edicio-de-la-gala-de-dansa-de-ballarins-mallorquins\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/event\\\/2a-edicio-de-la-gala-de-dansa-de-ballarins-mallorquins\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Gala-de-Dansa-Ballarins-Mallorquins-2025-Bellver.jpg\",\"datePublished\":\"2025-07-25T09:56:08+00:00\",\"description\":\"Disfruta la 2\u00aa Gala de Dansa de Ballarins Mallorquins en el Castell de Bellver, 12\u202fagosto\u202f2025 a las\u202f21\u202fh. Espect\u00e1culo \u00fanico con talento local. Entradas ya a la venta.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/event\\\/2a-edicio-de-la-gala-de-dansa-de-ballarins-mallorquins\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/visitpalma.com\\\/es\\\/event\\\/2a-edicio-de-la-gala-de-dansa-de-ballarins-mallorquins\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/event\\\/2a-edicio-de-la-gala-de-dansa-de-ballarins-mallorquins\\\/#primaryimage\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Gala-de-Dansa-Ballarins-Mallorquins-2025-Bellver.jpg\",\"contentUrl\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Gala-de-Dansa-Ballarins-Mallorquins-2025-Bellver.jpg\",\"width\":600,\"height\":315,\"caption\":\"Gala-de-Dansa-Ballarins-Mallorquins-2025-Bellver\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/event\\\/2a-edicio-de-la-gala-de-dansa-de-ballarins-mallorquins\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventos\",\"item\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"2\u00aa edici\u00f3 de la Gala de Dansa de Ballarins Mallorquins\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/\",\"name\":\"Visit Palma\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3n Turismo Palma de Mallorca 365\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Logo-Passion-for-Palma-de-Mallorca.svg\",\"contentUrl\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Logo-Passion-for-Palma-de-Mallorca.svg\",\"width\":377,\"height\":377,\"caption\":\"Fundaci\u00f3n Turismo Palma de Mallorca 365\"},\"image\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/passionforpalma\",\"https:\\\/\\\/x.com\\\/passionforpalma\",\"https:\\\/\\\/www.instagram.com\\\/passionforpalma_\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCALF2N1FRnmAZYBttkQjedA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"2\u00aa Gala de Dansa Ballarins Mallorquins \u2013 Bellver 12 ago 2025","description":"Disfruta la 2\u00aa Gala de Dansa de Ballarins Mallorquins en el Castell de Bellver, 12\u202fagosto\u202f2025 a las\u202f21\u202fh. Espect\u00e1culo \u00fanico con talento local. Entradas ya a la venta.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/visitpalma.com\/es\/event\/2a-edicio-de-la-gala-de-dansa-de-ballarins-mallorquins\/","og_locale":"es_ES","og_type":"article","og_title":"2\u00aa Gala de Dansa Ballarins Mallorquins \u2013 Bellver 12 ago 2025","og_description":"Disfruta la 2\u00aa Gala de Dansa de Ballarins Mallorquins en el Castell de Bellver, 12\u202fagosto\u202f2025 a las\u202f21\u202fh. Espect\u00e1culo \u00fanico con talento local. Entradas ya a la venta.","og_url":"https:\/\/visitpalma.com\/es\/event\/2a-edicio-de-la-gala-de-dansa-de-ballarins-mallorquins\/","og_site_name":"Visit Palma","article_publisher":"https:\/\/www.facebook.com\/passionforpalma","og_image":[{"width":600,"height":315,"url":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/07\/Gala-de-Dansa-Ballarins-Mallorquins-2025-Bellver.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@passionforpalma","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/visitpalma.com\/es\/event\/2a-edicio-de-la-gala-de-dansa-de-ballarins-mallorquins\/","url":"https:\/\/visitpalma.com\/es\/event\/2a-edicio-de-la-gala-de-dansa-de-ballarins-mallorquins\/","name":"2\u00aa Gala de Dansa Ballarins Mallorquins \u2013 Bellver 12 ago 2025","isPartOf":{"@id":"https:\/\/visitpalma.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/visitpalma.com\/es\/event\/2a-edicio-de-la-gala-de-dansa-de-ballarins-mallorquins\/#primaryimage"},"image":{"@id":"https:\/\/visitpalma.com\/es\/event\/2a-edicio-de-la-gala-de-dansa-de-ballarins-mallorquins\/#primaryimage"},"thumbnailUrl":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/07\/Gala-de-Dansa-Ballarins-Mallorquins-2025-Bellver.jpg","datePublished":"2025-07-25T09:56:08+00:00","description":"Disfruta la 2\u00aa Gala de Dansa de Ballarins Mallorquins en el Castell de Bellver, 12\u202fagosto\u202f2025 a las\u202f21\u202fh. Espect\u00e1culo \u00fanico con talento local. Entradas ya a la venta.","breadcrumb":{"@id":"https:\/\/visitpalma.com\/es\/event\/2a-edicio-de-la-gala-de-dansa-de-ballarins-mallorquins\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/visitpalma.com\/es\/event\/2a-edicio-de-la-gala-de-dansa-de-ballarins-mallorquins\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/visitpalma.com\/es\/event\/2a-edicio-de-la-gala-de-dansa-de-ballarins-mallorquins\/#primaryimage","url":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/07\/Gala-de-Dansa-Ballarins-Mallorquins-2025-Bellver.jpg","contentUrl":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/07\/Gala-de-Dansa-Ballarins-Mallorquins-2025-Bellver.jpg","width":600,"height":315,"caption":"Gala-de-Dansa-Ballarins-Mallorquins-2025-Bellver"},{"@type":"BreadcrumbList","@id":"https:\/\/visitpalma.com\/es\/event\/2a-edicio-de-la-gala-de-dansa-de-ballarins-mallorquins\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/visitpalma.com\/es\/"},{"@type":"ListItem","position":2,"name":"Eventos","item":"https:\/\/visitpalma.com\/es\/events\/"},{"@type":"ListItem","position":3,"name":"2\u00aa edici\u00f3 de la Gala de Dansa de Ballarins Mallorquins"}]},{"@type":"WebSite","@id":"https:\/\/visitpalma.com\/es\/#website","url":"https:\/\/visitpalma.com\/es\/","name":"Visit Palma","description":"","publisher":{"@id":"https:\/\/visitpalma.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/visitpalma.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/visitpalma.com\/es\/#organization","name":"Fundaci\u00f3n Turismo Palma de Mallorca 365","url":"https:\/\/visitpalma.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/visitpalma.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/05\/Logo-Passion-for-Palma-de-Mallorca.svg","contentUrl":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/05\/Logo-Passion-for-Palma-de-Mallorca.svg","width":377,"height":377,"caption":"Fundaci\u00f3n Turismo Palma de Mallorca 365"},"image":{"@id":"https:\/\/visitpalma.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/passionforpalma","https:\/\/x.com\/passionforpalma","https:\/\/www.instagram.com\/passionforpalma_\/","https:\/\/www.youtube.com\/channel\/UCALF2N1FRnmAZYBttkQjedA"]}]}},"_links":{"self":[{"href":"https:\/\/visitpalma.com\/es\/wp-json\/wp\/v2\/tribe_events\/15466","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visitpalma.com\/es\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/visitpalma.com\/es\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/visitpalma.com\/es\/wp-json\/wp\/v2\/users\/4"}],"version-history":[{"count":1,"href":"https:\/\/visitpalma.com\/es\/wp-json\/wp\/v2\/tribe_events\/15466\/revisions"}],"predecessor-version":[{"id":15471,"href":"https:\/\/visitpalma.com\/es\/wp-json\/wp\/v2\/tribe_events\/15466\/revisions\/15471"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visitpalma.com\/es\/wp-json\/wp\/v2\/media\/15467"}],"wp:attachment":[{"href":"https:\/\/visitpalma.com\/es\/wp-json\/wp\/v2\/media?parent=15466"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visitpalma.com\/es\/wp-json\/wp\/v2\/tags?post=15466"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/visitpalma.com\/es\/wp-json\/wp\/v2\/tribe_events_cat?post=15466"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}