{"id":15594,"date":"2025-07-29T12:37:29","date_gmt":"2025-07-29T10:37:29","guid":{"rendered":"https:\/\/visitpalma.com\/event\/leon-gieco-y-agarrate-catalina\/"},"modified":"2025-07-30T13:01:14","modified_gmt":"2025-07-30T11:01:14","slug":"leon-gieco-y-agarrate-catalina","status":"publish","type":"tribe_events","link":"https:\/\/visitpalma.com\/en\/event\/leon-gieco-y-agarrate-catalina\/","title":{"rendered":"Le\u00f3n Gieco y Ag\u00e1rrate Catalina"},"content":{"rendered":"<p data-start=\"91\" data-end=\"494\">The acclaimed Uruguayan murga <em data-start=\"136\" data-end=\"155\">Agarrate Catalina<\/em> and iconic Argentine singer-songwriter Le\u00f3n Gieco unite in a unique show blending emotion, social commentary, and powerful stagecraft. With over 20 years of global acclaim, Agarrate Catalina revolutionized carnival with its satirical, musical style, while Gieco\u2019s legendary songs, like <em data-start=\"442\" data-end=\"463\">Solo le pido a Dios<\/em>, remain anthems of conscience.<\/p>\n<p data-start=\"496\" data-end=\"723\">The tour kicks off on August 28 in Palma de Mallorca and continues through Valencia, Barcelona, and Madrid, with more dates possible. This is more than a concert\u2014it&#8217;s a heartfelt celebration of music, words, and cultural unity.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>The acclaimed Uruguayan murga Agarrate Catalina and iconic Argentine singer-songwriter Le\u00f3n Gieco unite in a unique show blending emotion, social commentary, and powerful stagecraft. With over 20 years of global [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":15555,"template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[170],"class_list":["post-15594","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-music-and-dance","cat_music-and-dance"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le\u00f3n Gieco y Agarrate Catalina en Palma \u2013 28 agosto<\/title>\n<meta name=\"description\" content=\"Le\u00f3n Gieco y la murga Agarrate Catalina unen fuerzas en un show \u00fanico el 28 de agosto en Es Gremi. M\u00fasica, cr\u00edtica y emoci\u00f3n en directo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/visitpalma.com\/en\/event\/leon-gieco-y-agarrate-catalina\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le\u00f3n Gieco y Agarrate Catalina en Palma \u2013 28 agosto\" \/>\n<meta property=\"og:description\" content=\"Le\u00f3n Gieco y la murga Agarrate Catalina unen fuerzas en un show \u00fanico el 28 de agosto en Es Gremi. M\u00fasica, cr\u00edtica y emoci\u00f3n en directo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/visitpalma.com\/en\/event\/leon-gieco-y-agarrate-catalina\/\" \/>\n<meta property=\"og:site_name\" content=\"Visit Palma\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/passionforpalma\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-30T11:01:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/07\/Leon-Gieco-Agarrate-Catalina-Palma-20251.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@passionforpalma\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/en\\\/event\\\/leon-gieco-y-agarrate-catalina\\\/\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/en\\\/event\\\/leon-gieco-y-agarrate-catalina\\\/\",\"name\":\"Le\u00f3n Gieco y Agarrate Catalina en Palma \u2013 28 agosto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/en\\\/event\\\/leon-gieco-y-agarrate-catalina\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/en\\\/event\\\/leon-gieco-y-agarrate-catalina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Leon-Gieco-Agarrate-Catalina-Palma-20251.jpg\",\"datePublished\":\"2025-07-29T10:37:29+00:00\",\"dateModified\":\"2025-07-30T11:01:14+00:00\",\"description\":\"Le\u00f3n Gieco y la murga Agarrate Catalina unen fuerzas en un show \u00fanico el 28 de agosto en Es Gremi. M\u00fasica, cr\u00edtica y emoci\u00f3n en directo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/en\\\/event\\\/leon-gieco-y-agarrate-catalina\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/visitpalma.com\\\/en\\\/event\\\/leon-gieco-y-agarrate-catalina\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/en\\\/event\\\/leon-gieco-y-agarrate-catalina\\\/#primaryimage\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Leon-Gieco-Agarrate-Catalina-Palma-20251.jpg\",\"contentUrl\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Leon-Gieco-Agarrate-Catalina-Palma-20251.jpg\",\"width\":960,\"height\":640,\"caption\":\"Leon-Gieco-Agarrate-Catalina-Palma-2025\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/en\\\/event\\\/leon-gieco-y-agarrate-catalina\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/visitpalma.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"https:\\\/\\\/visitpalma.com\\\/en\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Le\u00f3n Gieco y Ag\u00e1rrate Catalina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/en\\\/\",\"name\":\"Visit Palma\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/visitpalma.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/en\\\/#organization\",\"name\":\"Fundaci\u00f3n Turismo Palma de Mallorca 365\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Logo-Passion-for-Palma-de-Mallorca.svg\",\"contentUrl\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Logo-Passion-for-Palma-de-Mallorca.svg\",\"width\":377,\"height\":377,\"caption\":\"Fundaci\u00f3n Turismo Palma de Mallorca 365\"},\"image\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/passionforpalma\",\"https:\\\/\\\/x.com\\\/passionforpalma\",\"https:\\\/\\\/www.instagram.com\\\/passionforpalma_\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCALF2N1FRnmAZYBttkQjedA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le\u00f3n Gieco y Agarrate Catalina en Palma \u2013 28 agosto","description":"Le\u00f3n Gieco y la murga Agarrate Catalina unen fuerzas en un show \u00fanico el 28 de agosto en Es Gremi. M\u00fasica, cr\u00edtica y emoci\u00f3n en directo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/visitpalma.com\/en\/event\/leon-gieco-y-agarrate-catalina\/","og_locale":"en_US","og_type":"article","og_title":"Le\u00f3n Gieco y Agarrate Catalina en Palma \u2013 28 agosto","og_description":"Le\u00f3n Gieco y la murga Agarrate Catalina unen fuerzas en un show \u00fanico el 28 de agosto en Es Gremi. M\u00fasica, cr\u00edtica y emoci\u00f3n en directo.","og_url":"https:\/\/visitpalma.com\/en\/event\/leon-gieco-y-agarrate-catalina\/","og_site_name":"Visit Palma","article_publisher":"https:\/\/www.facebook.com\/passionforpalma","article_modified_time":"2025-07-30T11:01:14+00:00","og_image":[{"width":960,"height":640,"url":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/07\/Leon-Gieco-Agarrate-Catalina-Palma-20251.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@passionforpalma","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/visitpalma.com\/en\/event\/leon-gieco-y-agarrate-catalina\/","url":"https:\/\/visitpalma.com\/en\/event\/leon-gieco-y-agarrate-catalina\/","name":"Le\u00f3n Gieco y Agarrate Catalina en Palma \u2013 28 agosto","isPartOf":{"@id":"https:\/\/visitpalma.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/visitpalma.com\/en\/event\/leon-gieco-y-agarrate-catalina\/#primaryimage"},"image":{"@id":"https:\/\/visitpalma.com\/en\/event\/leon-gieco-y-agarrate-catalina\/#primaryimage"},"thumbnailUrl":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/07\/Leon-Gieco-Agarrate-Catalina-Palma-20251.jpg","datePublished":"2025-07-29T10:37:29+00:00","dateModified":"2025-07-30T11:01:14+00:00","description":"Le\u00f3n Gieco y la murga Agarrate Catalina unen fuerzas en un show \u00fanico el 28 de agosto en Es Gremi. M\u00fasica, cr\u00edtica y emoci\u00f3n en directo.","breadcrumb":{"@id":"https:\/\/visitpalma.com\/en\/event\/leon-gieco-y-agarrate-catalina\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/visitpalma.com\/en\/event\/leon-gieco-y-agarrate-catalina\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/visitpalma.com\/en\/event\/leon-gieco-y-agarrate-catalina\/#primaryimage","url":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/07\/Leon-Gieco-Agarrate-Catalina-Palma-20251.jpg","contentUrl":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/07\/Leon-Gieco-Agarrate-Catalina-Palma-20251.jpg","width":960,"height":640,"caption":"Leon-Gieco-Agarrate-Catalina-Palma-2025"},{"@type":"BreadcrumbList","@id":"https:\/\/visitpalma.com\/en\/event\/leon-gieco-y-agarrate-catalina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/visitpalma.com\/en\/"},{"@type":"ListItem","position":2,"name":"Events","item":"https:\/\/visitpalma.com\/en\/events\/"},{"@type":"ListItem","position":3,"name":"Le\u00f3n Gieco y Ag\u00e1rrate Catalina"}]},{"@type":"WebSite","@id":"https:\/\/visitpalma.com\/en\/#website","url":"https:\/\/visitpalma.com\/en\/","name":"Visit Palma","description":"","publisher":{"@id":"https:\/\/visitpalma.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/visitpalma.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/visitpalma.com\/en\/#organization","name":"Fundaci\u00f3n Turismo Palma de Mallorca 365","url":"https:\/\/visitpalma.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/visitpalma.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/05\/Logo-Passion-for-Palma-de-Mallorca.svg","contentUrl":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/05\/Logo-Passion-for-Palma-de-Mallorca.svg","width":377,"height":377,"caption":"Fundaci\u00f3n Turismo Palma de Mallorca 365"},"image":{"@id":"https:\/\/visitpalma.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/passionforpalma","https:\/\/x.com\/passionforpalma","https:\/\/www.instagram.com\/passionforpalma_\/","https:\/\/www.youtube.com\/channel\/UCALF2N1FRnmAZYBttkQjedA"]}]}},"_links":{"self":[{"href":"https:\/\/visitpalma.com\/en\/wp-json\/wp\/v2\/tribe_events\/15594","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visitpalma.com\/en\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/visitpalma.com\/en\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/visitpalma.com\/en\/wp-json\/wp\/v2\/users\/4"}],"version-history":[{"count":1,"href":"https:\/\/visitpalma.com\/en\/wp-json\/wp\/v2\/tribe_events\/15594\/revisions"}],"predecessor-version":[{"id":15595,"href":"https:\/\/visitpalma.com\/en\/wp-json\/wp\/v2\/tribe_events\/15594\/revisions\/15595"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visitpalma.com\/en\/wp-json\/wp\/v2\/media\/15555"}],"wp:attachment":[{"href":"https:\/\/visitpalma.com\/en\/wp-json\/wp\/v2\/media?parent=15594"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visitpalma.com\/en\/wp-json\/wp\/v2\/tags?post=15594"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/visitpalma.com\/en\/wp-json\/wp\/v2\/tribe_events_cat?post=15594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}