{"id":19497,"date":"2026-03-19T10:56:54","date_gmt":"2026-03-19T09:56:54","guid":{"rendered":"https:\/\/visitpalma.com\/event\/fira-del-ram-palma-2026\/"},"modified":"2026-03-19T10:56:54","modified_gmt":"2026-03-19T09:56:54","slug":"fira-del-ram-palma-2026","status":"publish","type":"tribe_events","link":"https:\/\/visitpalma.com\/de\/event\/fira-del-ram-palma-2026\/","title":{"rendered":"FIRA DEL RAM &#8211; PALMA 2026"},"content":{"rendered":"<p>Die <strong>Fira del Ram 2026<\/strong> kehrt als eines der am meisten erwarteten Ereignisse des Jahres nach Palma zur\u00fcck.<\/p>\n<p>Dieser tempor\u00e4re Vergn\u00fcgungspark vereint Spa\u00df, Tradition und Gastronomie f\u00fcr alle Altersgruppen. Mehrere Wochen lang genie\u00dfen Einheimische und Besucher spannende Attraktionen und St\u00e4nde mit typischen Speisen. Jeden Abend erf\u00fcllt eine festliche Stimmung die Stadt mit Lichtern, Musik und Freude. Ein ideales Angebot f\u00fcr Familien, Freundesgruppen und Jahrmarktsliebhaber. Au\u00dferdem gibt es auf der Jahrmarkt Kinderbereiche und Attraktionen f\u00fcr die Kleinsten.   <\/p>\n<p>Die Fira del Ram ist ein absolutes Muss im Fr\u00fchling auf Mallorca. Ein Besuch dort bietet die Gelegenheit, eine der beliebtesten Traditionen der Insel kennenzulernen. <\/p>\n<p>Weitere Informationen zum Programm und zu weiteren Details finden Sie auf dem entsprechenden <a href=\"https:\/\/www.instagram.com\/feriadebaleares?igsh=Mjd6Z2djdHd6bW4y\">Instagram-Profil<\/a>.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Fira del Ram 2026 kehrt als eines der am meisten erwarteten Ereignisse des Jahres nach Palma zur\u00fcck. Dieser tempor\u00e4re Vergn\u00fcgungspark vereint Spa\u00df, Tradition und Gastronomie f\u00fcr alle Altersgruppen. Mehrere [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":19496,"template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[189],"class_list":["post-19497","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-fiestas-y-tradiciones-de","cat_fiestas-y-tradiciones-de"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ira del Ram Palma 2026: Jahrmarkt &amp; Attraktionen<\/title>\n<meta name=\"description\" content=\"Erlebe die Fira del Ram in Palma mit Fahrgesch\u00e4ften, Spa\u00df und Familienatmosph\u00e4re. Ein Highlight und eines der beliebtesten Events des Jahres.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/visitpalma.com\/de\/event\/fira-del-ram-palma-2026\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ira del Ram Palma 2026: Jahrmarkt &amp; Attraktionen\" \/>\n<meta property=\"og:description\" content=\"Erlebe die Fira del Ram in Palma mit Fahrgesch\u00e4ften, Spa\u00df und Familienatmosph\u00e4re. Ein Highlight und eines der beliebtesten Events des Jahres.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/visitpalma.com\/de\/event\/fira-del-ram-palma-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Visit Palma\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/passionforpalma\" \/>\n<meta property=\"og:image\" content=\"https:\/\/visitpalma.com\/wp-content\/uploads\/2026\/03\/fira-del-ram-2026-palma.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@passionforpalma\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/event\\\/fira-del-ram-palma-2026\\\/\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/event\\\/fira-del-ram-palma-2026\\\/\",\"name\":\"ira del Ram Palma 2026: Jahrmarkt & Attraktionen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/event\\\/fira-del-ram-palma-2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/event\\\/fira-del-ram-palma-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/fira-del-ram-2026-palma.jpg\",\"datePublished\":\"2026-03-19T09:56:54+00:00\",\"description\":\"Erlebe die Fira del Ram in Palma mit Fahrgesch\u00e4ften, Spa\u00df und Familienatmosph\u00e4re. Ein Highlight und eines der beliebtesten Events des Jahres.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/event\\\/fira-del-ram-palma-2026\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/visitpalma.com\\\/de\\\/event\\\/fira-del-ram-palma-2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/event\\\/fira-del-ram-palma-2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/fira-del-ram-2026-palma.jpg\",\"contentUrl\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/fira-del-ram-2026-palma.jpg\",\"width\":1080,\"height\":1350,\"caption\":\"fira del ram 2026 palma\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/event\\\/fira-del-ram-palma-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veranstaltungen\",\"item\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"FIRA DEL RAM &#8211; PALMA 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/\",\"name\":\"Visit Palma\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/#organization\",\"name\":\"Fundaci\u00f3n Turismo Palma de Mallorca 365\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Logo-Passion-for-Palma-de-Mallorca.svg\",\"contentUrl\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Logo-Passion-for-Palma-de-Mallorca.svg\",\"width\":377,\"height\":377,\"caption\":\"Fundaci\u00f3n Turismo Palma de Mallorca 365\"},\"image\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/passionforpalma\",\"https:\\\/\\\/x.com\\\/passionforpalma\",\"https:\\\/\\\/www.instagram.com\\\/passionforpalma_\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCALF2N1FRnmAZYBttkQjedA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ira del Ram Palma 2026: Jahrmarkt & Attraktionen","description":"Erlebe die Fira del Ram in Palma mit Fahrgesch\u00e4ften, Spa\u00df und Familienatmosph\u00e4re. Ein Highlight und eines der beliebtesten Events des Jahres.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/visitpalma.com\/de\/event\/fira-del-ram-palma-2026\/","og_locale":"de_DE","og_type":"article","og_title":"ira del Ram Palma 2026: Jahrmarkt & Attraktionen","og_description":"Erlebe die Fira del Ram in Palma mit Fahrgesch\u00e4ften, Spa\u00df und Familienatmosph\u00e4re. Ein Highlight und eines der beliebtesten Events des Jahres.","og_url":"https:\/\/visitpalma.com\/de\/event\/fira-del-ram-palma-2026\/","og_site_name":"Visit Palma","article_publisher":"https:\/\/www.facebook.com\/passionforpalma","og_image":[{"width":1080,"height":1350,"url":"https:\/\/visitpalma.com\/wp-content\/uploads\/2026\/03\/fira-del-ram-2026-palma.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@passionforpalma","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/visitpalma.com\/de\/event\/fira-del-ram-palma-2026\/","url":"https:\/\/visitpalma.com\/de\/event\/fira-del-ram-palma-2026\/","name":"ira del Ram Palma 2026: Jahrmarkt & Attraktionen","isPartOf":{"@id":"https:\/\/visitpalma.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/visitpalma.com\/de\/event\/fira-del-ram-palma-2026\/#primaryimage"},"image":{"@id":"https:\/\/visitpalma.com\/de\/event\/fira-del-ram-palma-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/visitpalma.com\/wp-content\/uploads\/2026\/03\/fira-del-ram-2026-palma.jpg","datePublished":"2026-03-19T09:56:54+00:00","description":"Erlebe die Fira del Ram in Palma mit Fahrgesch\u00e4ften, Spa\u00df und Familienatmosph\u00e4re. Ein Highlight und eines der beliebtesten Events des Jahres.","breadcrumb":{"@id":"https:\/\/visitpalma.com\/de\/event\/fira-del-ram-palma-2026\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/visitpalma.com\/de\/event\/fira-del-ram-palma-2026\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/visitpalma.com\/de\/event\/fira-del-ram-palma-2026\/#primaryimage","url":"https:\/\/visitpalma.com\/wp-content\/uploads\/2026\/03\/fira-del-ram-2026-palma.jpg","contentUrl":"https:\/\/visitpalma.com\/wp-content\/uploads\/2026\/03\/fira-del-ram-2026-palma.jpg","width":1080,"height":1350,"caption":"fira del ram 2026 palma"},{"@type":"BreadcrumbList","@id":"https:\/\/visitpalma.com\/de\/event\/fira-del-ram-palma-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/visitpalma.com\/de\/"},{"@type":"ListItem","position":2,"name":"Veranstaltungen","item":"https:\/\/visitpalma.com\/de\/events\/"},{"@type":"ListItem","position":3,"name":"FIRA DEL RAM &#8211; PALMA 2026"}]},{"@type":"WebSite","@id":"https:\/\/visitpalma.com\/de\/#website","url":"https:\/\/visitpalma.com\/de\/","name":"Visit Palma","description":"","publisher":{"@id":"https:\/\/visitpalma.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/visitpalma.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/visitpalma.com\/de\/#organization","name":"Fundaci\u00f3n Turismo Palma de Mallorca 365","url":"https:\/\/visitpalma.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/visitpalma.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/05\/Logo-Passion-for-Palma-de-Mallorca.svg","contentUrl":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/05\/Logo-Passion-for-Palma-de-Mallorca.svg","width":377,"height":377,"caption":"Fundaci\u00f3n Turismo Palma de Mallorca 365"},"image":{"@id":"https:\/\/visitpalma.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/passionforpalma","https:\/\/x.com\/passionforpalma","https:\/\/www.instagram.com\/passionforpalma_\/","https:\/\/www.youtube.com\/channel\/UCALF2N1FRnmAZYBttkQjedA"]}]}},"_links":{"self":[{"href":"https:\/\/visitpalma.com\/de\/wp-json\/wp\/v2\/tribe_events\/19497","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visitpalma.com\/de\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/visitpalma.com\/de\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/visitpalma.com\/de\/wp-json\/wp\/v2\/users\/4"}],"version-history":[{"count":0,"href":"https:\/\/visitpalma.com\/de\/wp-json\/wp\/v2\/tribe_events\/19497\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visitpalma.com\/de\/wp-json\/wp\/v2\/media\/19496"}],"wp:attachment":[{"href":"https:\/\/visitpalma.com\/de\/wp-json\/wp\/v2\/media?parent=19497"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visitpalma.com\/de\/wp-json\/wp\/v2\/tags?post=19497"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/visitpalma.com\/de\/wp-json\/wp\/v2\/tribe_events_cat?post=19497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}