{"id":16880,"date":"2025-10-06T10:05:39","date_gmt":"2025-10-06T08:05:39","guid":{"rendered":"https:\/\/visitpalma.com\/event\/8o-congreso-despertar-emociones\/"},"modified":"2025-10-06T10:05:39","modified_gmt":"2025-10-06T08:05:39","slug":"8o-congreso-despertar-emociones","status":"publish","type":"tribe_events","link":"https:\/\/visitpalma.com\/de\/event\/8o-congreso-despertar-emociones\/","title":{"rendered":"8\u00ba Congreso Despertar Emociones"},"content":{"rendered":"<p>Der <strong data-start=\"170\" data-end=\"205\">8. Kongress Despertar Emociones<\/strong> ist eine reflektierende Veranstaltung mit Referent:innen und Programmpunkten rund um emotionales Wohlbefinden, Selbsterkenntnis und menschliche Verbindung. An mehreren Tagen nehmen Teilnehmende an Vortr\u00e4gen, erlebensorientierten Workshops und Austauschformaten teil, um Emotionen zu steuern, Empathie zu f\u00f6rdern und das Leben mit achtsamen Praktiken zu bereichern. Eine Chance f\u00fcr inneres Wachstum in Gemeinschaft und bedeutsamen Erfahrungen.  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der 8. Kongress Despertar Emociones ist eine reflektierende Veranstaltung mit Referent:innen und Programmpunkten rund um emotionales Wohlbefinden, Selbsterkenntnis und menschliche Verbindung. An mehreren Tagen nehmen Teilnehmende an Vortr\u00e4gen, erlebensorientierten Workshops [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":16876,"template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[180],"class_list":["post-16880","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-sonstige-veranstaltungen","cat_sonstige-veranstaltungen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>8. Despertar Emociones Kongress in Palma<\/title>\n<meta name=\"description\" content=\"Nimm teil am 8. Congreso Despertar Emociones in Palma. Vortr\u00e4ge, Workshops und Erfahrungsr\u00e4ume f\u00fcr emotionales Wohlbefinden und pers\u00f6nliches Wachstum.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/visitpalma.com\/de\/event\/8o-congreso-despertar-emociones\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"8. Despertar Emociones Kongress in Palma\" \/>\n<meta property=\"og:description\" content=\"Nimm teil am 8. Congreso Despertar Emociones in Palma. Vortr\u00e4ge, Workshops und Erfahrungsr\u00e4ume f\u00fcr emotionales Wohlbefinden und pers\u00f6nliches Wachstum.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/visitpalma.com\/de\/event\/8o-congreso-despertar-emociones\/\" \/>\n<meta property=\"og:site_name\" content=\"Visit Palma\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/passionforpalma\" \/>\n<meta property=\"og:image\" content=\"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/10\/Congreso-Despertar-Emociones-Palma.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@passionforpalma\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/event\\\/8o-congreso-despertar-emociones\\\/\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/event\\\/8o-congreso-despertar-emociones\\\/\",\"name\":\"8. Despertar Emociones Kongress in Palma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/event\\\/8o-congreso-despertar-emociones\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/event\\\/8o-congreso-despertar-emociones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Congreso-Despertar-Emociones-Palma.jpg\",\"datePublished\":\"2025-10-06T08:05:39+00:00\",\"description\":\"Nimm teil am 8. Congreso Despertar Emociones in Palma. Vortr\u00e4ge, Workshops und Erfahrungsr\u00e4ume f\u00fcr emotionales Wohlbefinden und pers\u00f6nliches Wachstum.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/event\\\/8o-congreso-despertar-emociones\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/visitpalma.com\\\/de\\\/event\\\/8o-congreso-despertar-emociones\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/event\\\/8o-congreso-despertar-emociones\\\/#primaryimage\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Congreso-Despertar-Emociones-Palma.jpg\",\"contentUrl\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Congreso-Despertar-Emociones-Palma.jpg\",\"width\":900,\"height\":600,\"caption\":\"Congreso Despertar Emociones Palma\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/event\\\/8o-congreso-despertar-emociones\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veranstaltungen\",\"item\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"8\u00ba Congreso Despertar Emociones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/\",\"name\":\"Visit Palma\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/#organization\",\"name\":\"Fundaci\u00f3n Turismo Palma de Mallorca 365\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Logo-Passion-for-Palma-de-Mallorca.svg\",\"contentUrl\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Logo-Passion-for-Palma-de-Mallorca.svg\",\"width\":377,\"height\":377,\"caption\":\"Fundaci\u00f3n Turismo Palma de Mallorca 365\"},\"image\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/passionforpalma\",\"https:\\\/\\\/x.com\\\/passionforpalma\",\"https:\\\/\\\/www.instagram.com\\\/passionforpalma_\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCALF2N1FRnmAZYBttkQjedA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"8. Despertar Emociones Kongress in Palma","description":"Nimm teil am 8. Congreso Despertar Emociones in Palma. Vortr\u00e4ge, Workshops und Erfahrungsr\u00e4ume f\u00fcr emotionales Wohlbefinden und pers\u00f6nliches Wachstum.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/visitpalma.com\/de\/event\/8o-congreso-despertar-emociones\/","og_locale":"de_DE","og_type":"article","og_title":"8. Despertar Emociones Kongress in Palma","og_description":"Nimm teil am 8. Congreso Despertar Emociones in Palma. Vortr\u00e4ge, Workshops und Erfahrungsr\u00e4ume f\u00fcr emotionales Wohlbefinden und pers\u00f6nliches Wachstum.","og_url":"https:\/\/visitpalma.com\/de\/event\/8o-congreso-despertar-emociones\/","og_site_name":"Visit Palma","article_publisher":"https:\/\/www.facebook.com\/passionforpalma","og_image":[{"width":900,"height":600,"url":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/10\/Congreso-Despertar-Emociones-Palma.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@passionforpalma","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/visitpalma.com\/de\/event\/8o-congreso-despertar-emociones\/","url":"https:\/\/visitpalma.com\/de\/event\/8o-congreso-despertar-emociones\/","name":"8. Despertar Emociones Kongress in Palma","isPartOf":{"@id":"https:\/\/visitpalma.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/visitpalma.com\/de\/event\/8o-congreso-despertar-emociones\/#primaryimage"},"image":{"@id":"https:\/\/visitpalma.com\/de\/event\/8o-congreso-despertar-emociones\/#primaryimage"},"thumbnailUrl":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/10\/Congreso-Despertar-Emociones-Palma.jpg","datePublished":"2025-10-06T08:05:39+00:00","description":"Nimm teil am 8. Congreso Despertar Emociones in Palma. Vortr\u00e4ge, Workshops und Erfahrungsr\u00e4ume f\u00fcr emotionales Wohlbefinden und pers\u00f6nliches Wachstum.","breadcrumb":{"@id":"https:\/\/visitpalma.com\/de\/event\/8o-congreso-despertar-emociones\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/visitpalma.com\/de\/event\/8o-congreso-despertar-emociones\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/visitpalma.com\/de\/event\/8o-congreso-despertar-emociones\/#primaryimage","url":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/10\/Congreso-Despertar-Emociones-Palma.jpg","contentUrl":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/10\/Congreso-Despertar-Emociones-Palma.jpg","width":900,"height":600,"caption":"Congreso Despertar Emociones Palma"},{"@type":"BreadcrumbList","@id":"https:\/\/visitpalma.com\/de\/event\/8o-congreso-despertar-emociones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/visitpalma.com\/de\/"},{"@type":"ListItem","position":2,"name":"Veranstaltungen","item":"https:\/\/visitpalma.com\/de\/events\/"},{"@type":"ListItem","position":3,"name":"8\u00ba Congreso Despertar Emociones"}]},{"@type":"WebSite","@id":"https:\/\/visitpalma.com\/de\/#website","url":"https:\/\/visitpalma.com\/de\/","name":"Visit Palma","description":"","publisher":{"@id":"https:\/\/visitpalma.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/visitpalma.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/visitpalma.com\/de\/#organization","name":"Fundaci\u00f3n Turismo Palma de Mallorca 365","url":"https:\/\/visitpalma.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/visitpalma.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/05\/Logo-Passion-for-Palma-de-Mallorca.svg","contentUrl":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/05\/Logo-Passion-for-Palma-de-Mallorca.svg","width":377,"height":377,"caption":"Fundaci\u00f3n Turismo Palma de Mallorca 365"},"image":{"@id":"https:\/\/visitpalma.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/passionforpalma","https:\/\/x.com\/passionforpalma","https:\/\/www.instagram.com\/passionforpalma_\/","https:\/\/www.youtube.com\/channel\/UCALF2N1FRnmAZYBttkQjedA"]}]}},"_links":{"self":[{"href":"https:\/\/visitpalma.com\/de\/wp-json\/wp\/v2\/tribe_events\/16880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visitpalma.com\/de\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/visitpalma.com\/de\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/visitpalma.com\/de\/wp-json\/wp\/v2\/users\/4"}],"version-history":[{"count":0,"href":"https:\/\/visitpalma.com\/de\/wp-json\/wp\/v2\/tribe_events\/16880\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visitpalma.com\/de\/wp-json\/wp\/v2\/media\/16876"}],"wp:attachment":[{"href":"https:\/\/visitpalma.com\/de\/wp-json\/wp\/v2\/media?parent=16880"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visitpalma.com\/de\/wp-json\/wp\/v2\/tags?post=16880"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/visitpalma.com\/de\/wp-json\/wp\/v2\/tribe_events_cat?post=16880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}