{"id":15980,"date":"2025-09-06T10:58:05","date_gmt":"2025-09-06T08:58:05","guid":{"rendered":"https:\/\/visitpalma.com\/event\/eduardo-strauch\/"},"modified":"2025-09-06T10:58:05","modified_gmt":"2025-09-06T08:58:05","slug":"eduardo-strauch","status":"publish","type":"tribe_events","link":"https:\/\/visitpalma.com\/de\/event\/eduardo-strauch\/","title":{"rendered":"Eduardo Strauch"},"content":{"rendered":"<p data-start=\"224\" data-end=\"775\">Eduardo Strauch, geboren 1947 in Montevideo, ist einer der \u00dcberlebenden des Flugzeugabsturzes in den Anden 1972. Nach 72 Tagen in extremer K\u00e4lte, Lawinen und ohne Nahrung wurde seine \u00dcberlebensgeschichte weltweit zum Beispiel f\u00fcr Durchhalteverm\u00f6gen und Resilienz. Strauch, Architekt und Kunstliebhaber, teilt heute seine Erfahrungen in Vortr\u00e4gen, in denen er Werte wie F\u00fchrung, Teamarbeit, Umgang mit Angst und die Bedeutung von Leben, Familie und Freundschaft vermittelt.  <\/p>\n<p data-start=\"777\" data-end=\"939\">Verpassen Sie nicht seinen Vortrag am <strong data-start=\"809\" data-end=\"840\">3. Oktober im Trui Teatre<\/strong>, bei dem Eduardo Strauch mit seiner fesselnden Geschichte von Mut und \u00dcberleben in den Anden inspiriert.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eduardo Strauch, geboren 1947 in Montevideo, ist einer der \u00dcberlebenden des Flugzeugabsturzes in den Anden 1972. Nach 72 Tagen in extremer K\u00e4lte, Lawinen und ohne Nahrung wurde seine \u00dcberlebensgeschichte weltweit [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":15976,"template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[180],"class_list":["post-15980","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-sonstige-veranstaltungen","cat_sonstige-veranstaltungen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Eduardo Strauch im Trui Teatre - 3. Oktober<\/title>\n<meta name=\"description\" content=\"Erleben Sie Eduardo Strauchs inspirierenden Vortrag \u00fcber \u00dcberleben und Resilienz in den Anden am 3. Oktober im Trui Teatre.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/visitpalma.com\/de\/event\/eduardo-strauch\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eduardo Strauch im Trui Teatre - 3. Oktober\" \/>\n<meta property=\"og:description\" content=\"Erleben Sie Eduardo Strauchs inspirierenden Vortrag \u00fcber \u00dcberleben und Resilienz in den Anden am 3. Oktober im Trui Teatre.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/visitpalma.com\/de\/event\/eduardo-strauch\/\" \/>\n<meta property=\"og:site_name\" content=\"Visit Palma\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/passionforpalma\" \/>\n<meta property=\"og:image\" content=\"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/09\/Eduardo-Strauch-Palma-2025.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@passionforpalma\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/event\\\/eduardo-strauch\\\/\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/event\\\/eduardo-strauch\\\/\",\"name\":\"Eduardo Strauch im Trui Teatre - 3. Oktober\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/event\\\/eduardo-strauch\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/event\\\/eduardo-strauch\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Eduardo-Strauch-Palma-2025.jpg\",\"datePublished\":\"2025-09-06T08:58:05+00:00\",\"description\":\"Erleben Sie Eduardo Strauchs inspirierenden Vortrag \u00fcber \u00dcberleben und Resilienz in den Anden am 3. Oktober im Trui Teatre.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/event\\\/eduardo-strauch\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/visitpalma.com\\\/de\\\/event\\\/eduardo-strauch\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/event\\\/eduardo-strauch\\\/#primaryimage\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Eduardo-Strauch-Palma-2025.jpg\",\"contentUrl\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Eduardo-Strauch-Palma-2025.jpg\",\"width\":900,\"height\":600,\"caption\":\"Eduardo Strauch Palma 2025\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/event\\\/eduardo-strauch\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veranstaltungen\",\"item\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Eduardo Strauch\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/\",\"name\":\"Visit Palma\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/#organization\",\"name\":\"Fundaci\u00f3n Turismo Palma de Mallorca 365\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Logo-Passion-for-Palma-de-Mallorca.svg\",\"contentUrl\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Logo-Passion-for-Palma-de-Mallorca.svg\",\"width\":377,\"height\":377,\"caption\":\"Fundaci\u00f3n Turismo Palma de Mallorca 365\"},\"image\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/passionforpalma\",\"https:\\\/\\\/x.com\\\/passionforpalma\",\"https:\\\/\\\/www.instagram.com\\\/passionforpalma_\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCALF2N1FRnmAZYBttkQjedA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Eduardo Strauch im Trui Teatre - 3. Oktober","description":"Erleben Sie Eduardo Strauchs inspirierenden Vortrag \u00fcber \u00dcberleben und Resilienz in den Anden am 3. Oktober im Trui Teatre.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/visitpalma.com\/de\/event\/eduardo-strauch\/","og_locale":"de_DE","og_type":"article","og_title":"Eduardo Strauch im Trui Teatre - 3. Oktober","og_description":"Erleben Sie Eduardo Strauchs inspirierenden Vortrag \u00fcber \u00dcberleben und Resilienz in den Anden am 3. Oktober im Trui Teatre.","og_url":"https:\/\/visitpalma.com\/de\/event\/eduardo-strauch\/","og_site_name":"Visit Palma","article_publisher":"https:\/\/www.facebook.com\/passionforpalma","og_image":[{"width":900,"height":600,"url":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/09\/Eduardo-Strauch-Palma-2025.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@passionforpalma","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/visitpalma.com\/de\/event\/eduardo-strauch\/","url":"https:\/\/visitpalma.com\/de\/event\/eduardo-strauch\/","name":"Eduardo Strauch im Trui Teatre - 3. Oktober","isPartOf":{"@id":"https:\/\/visitpalma.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/visitpalma.com\/de\/event\/eduardo-strauch\/#primaryimage"},"image":{"@id":"https:\/\/visitpalma.com\/de\/event\/eduardo-strauch\/#primaryimage"},"thumbnailUrl":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/09\/Eduardo-Strauch-Palma-2025.jpg","datePublished":"2025-09-06T08:58:05+00:00","description":"Erleben Sie Eduardo Strauchs inspirierenden Vortrag \u00fcber \u00dcberleben und Resilienz in den Anden am 3. Oktober im Trui Teatre.","breadcrumb":{"@id":"https:\/\/visitpalma.com\/de\/event\/eduardo-strauch\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/visitpalma.com\/de\/event\/eduardo-strauch\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/visitpalma.com\/de\/event\/eduardo-strauch\/#primaryimage","url":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/09\/Eduardo-Strauch-Palma-2025.jpg","contentUrl":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/09\/Eduardo-Strauch-Palma-2025.jpg","width":900,"height":600,"caption":"Eduardo Strauch Palma 2025"},{"@type":"BreadcrumbList","@id":"https:\/\/visitpalma.com\/de\/event\/eduardo-strauch\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/visitpalma.com\/de\/"},{"@type":"ListItem","position":2,"name":"Veranstaltungen","item":"https:\/\/visitpalma.com\/de\/events\/"},{"@type":"ListItem","position":3,"name":"Eduardo Strauch"}]},{"@type":"WebSite","@id":"https:\/\/visitpalma.com\/de\/#website","url":"https:\/\/visitpalma.com\/de\/","name":"Visit Palma","description":"","publisher":{"@id":"https:\/\/visitpalma.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/visitpalma.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/visitpalma.com\/de\/#organization","name":"Fundaci\u00f3n Turismo Palma de Mallorca 365","url":"https:\/\/visitpalma.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/visitpalma.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/05\/Logo-Passion-for-Palma-de-Mallorca.svg","contentUrl":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/05\/Logo-Passion-for-Palma-de-Mallorca.svg","width":377,"height":377,"caption":"Fundaci\u00f3n Turismo Palma de Mallorca 365"},"image":{"@id":"https:\/\/visitpalma.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/passionforpalma","https:\/\/x.com\/passionforpalma","https:\/\/www.instagram.com\/passionforpalma_\/","https:\/\/www.youtube.com\/channel\/UCALF2N1FRnmAZYBttkQjedA"]}]}},"_links":{"self":[{"href":"https:\/\/visitpalma.com\/de\/wp-json\/wp\/v2\/tribe_events\/15980","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visitpalma.com\/de\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/visitpalma.com\/de\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/visitpalma.com\/de\/wp-json\/wp\/v2\/users\/4"}],"version-history":[{"count":0,"href":"https:\/\/visitpalma.com\/de\/wp-json\/wp\/v2\/tribe_events\/15980\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visitpalma.com\/de\/wp-json\/wp\/v2\/media\/15976"}],"wp:attachment":[{"href":"https:\/\/visitpalma.com\/de\/wp-json\/wp\/v2\/media?parent=15980"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visitpalma.com\/de\/wp-json\/wp\/v2\/tags?post=15980"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/visitpalma.com\/de\/wp-json\/wp\/v2\/tribe_events_cat?post=15980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}