{"id":15880,"date":"2025-08-11T10:41:40","date_gmt":"2025-08-11T08:41:40","guid":{"rendered":"https:\/\/visitpalma.com\/event\/bersuit\/"},"modified":"2025-08-11T10:41:40","modified_gmt":"2025-08-11T08:41:40","slug":"bersuit","status":"publish","type":"tribe_events","link":"https:\/\/visitpalma.com\/de\/event\/bersuit\/","title":{"rendered":"Bersuit"},"content":{"rendered":"<p>Von ihren Anf\u00e4ngen in der Underground-Szene von Buenos Aires bis hin zum ausverkauften River-Plate-Stadion hat Bersuit eine der intensivsten Karrieren des lateinamerikanischen Rocks aufgebaut, indem sie Rock mit Cumbia, Tango, Murga, Reggae oder Candombe verbanden und Texte mit scharfer sozialer und politischer Kritik schufen. Mit 15 Alben und dem aktuellen \u201cCocoliche Life\u201d (2024) bewahren sie ihre Energie und ihre enge Verbindung zu Spanien, die 2000 beim Festimad in Madrid begann und sich \u00fcber mehr als 20 Tourneen, fast 240 Konzerte und legend\u00e4re Songs wie \u201cLa del Toro\u201d, \u201cConvalescencia en Valencia\u201d, \u201cEl estallido\u201d oder \u201cLa Bolsa\u201d gefestigt hat. Nun feiern sie diese einzigartige Bindung zu ihrem spanischen Publikum mit der Tour \u201c25 Jahre mit Spanien\u201d \u2013 eine kulturelle Br\u00fccke, die Geschichte schreiben wird.  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Von ihren Anf\u00e4ngen in der Underground-Szene von Buenos Aires bis hin zum ausverkauften River-Plate-Stadion hat Bersuit eine der intensivsten Karrieren des lateinamerikanischen Rocks aufgebaut, indem sie Rock mit Cumbia, Tango, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":15876,"template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[171],"class_list":["post-15880","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-musik-und-tanz","cat_musik-und-tanz"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bersuit im Es Gremi \u2013 25 Jahre mit Spanien Tour<\/title>\n<meta name=\"description\" content=\"Erlebe Bersuit live im Es Gremi auf ihrer \u201c25 Jahre mit Spanien\u201d-Tour und feiere Musik, Geschichte und eine einzigartige kulturelle Verbindung.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/visitpalma.com\/de\/event\/bersuit\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bersuit im Es Gremi \u2013 25 Jahre mit Spanien Tour\" \/>\n<meta property=\"og:description\" content=\"Erlebe Bersuit live im Es Gremi auf ihrer \u201c25 Jahre mit Spanien\u201d-Tour und feiere Musik, Geschichte und eine einzigartige kulturelle Verbindung.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/visitpalma.com\/de\/event\/bersuit\/\" \/>\n<meta property=\"og:site_name\" content=\"Visit Palma\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/passionforpalma\" \/>\n<meta property=\"og:image\" content=\"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/08\/Bersuit-Palma-20251.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@passionforpalma\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/event\\\/bersuit\\\/\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/event\\\/bersuit\\\/\",\"name\":\"Bersuit im Es Gremi \u2013 25 Jahre mit Spanien Tour\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/event\\\/bersuit\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/event\\\/bersuit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Bersuit-Palma-20251.jpg\",\"datePublished\":\"2025-08-11T08:41:40+00:00\",\"description\":\"Erlebe Bersuit live im Es Gremi auf ihrer \u201c25 Jahre mit Spanien\u201d-Tour und feiere Musik, Geschichte und eine einzigartige kulturelle Verbindung.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/event\\\/bersuit\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/visitpalma.com\\\/de\\\/event\\\/bersuit\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/event\\\/bersuit\\\/#primaryimage\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Bersuit-Palma-20251.jpg\",\"contentUrl\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Bersuit-Palma-20251.jpg\",\"width\":960,\"height\":640,\"caption\":\"Bersuit-Palma-2025\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/event\\\/bersuit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veranstaltungen\",\"item\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bersuit\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/\",\"name\":\"Visit Palma\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/#organization\",\"name\":\"Fundaci\u00f3n Turismo Palma de Mallorca 365\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Logo-Passion-for-Palma-de-Mallorca.svg\",\"contentUrl\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Logo-Passion-for-Palma-de-Mallorca.svg\",\"width\":377,\"height\":377,\"caption\":\"Fundaci\u00f3n Turismo Palma de Mallorca 365\"},\"image\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/passionforpalma\",\"https:\\\/\\\/x.com\\\/passionforpalma\",\"https:\\\/\\\/www.instagram.com\\\/passionforpalma_\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCALF2N1FRnmAZYBttkQjedA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bersuit im Es Gremi \u2013 25 Jahre mit Spanien Tour","description":"Erlebe Bersuit live im Es Gremi auf ihrer \u201c25 Jahre mit Spanien\u201d-Tour und feiere Musik, Geschichte und eine einzigartige kulturelle Verbindung.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/visitpalma.com\/de\/event\/bersuit\/","og_locale":"de_DE","og_type":"article","og_title":"Bersuit im Es Gremi \u2013 25 Jahre mit Spanien Tour","og_description":"Erlebe Bersuit live im Es Gremi auf ihrer \u201c25 Jahre mit Spanien\u201d-Tour und feiere Musik, Geschichte und eine einzigartige kulturelle Verbindung.","og_url":"https:\/\/visitpalma.com\/de\/event\/bersuit\/","og_site_name":"Visit Palma","article_publisher":"https:\/\/www.facebook.com\/passionforpalma","og_image":[{"width":960,"height":640,"url":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/08\/Bersuit-Palma-20251.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@passionforpalma","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/visitpalma.com\/de\/event\/bersuit\/","url":"https:\/\/visitpalma.com\/de\/event\/bersuit\/","name":"Bersuit im Es Gremi \u2013 25 Jahre mit Spanien Tour","isPartOf":{"@id":"https:\/\/visitpalma.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/visitpalma.com\/de\/event\/bersuit\/#primaryimage"},"image":{"@id":"https:\/\/visitpalma.com\/de\/event\/bersuit\/#primaryimage"},"thumbnailUrl":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/08\/Bersuit-Palma-20251.jpg","datePublished":"2025-08-11T08:41:40+00:00","description":"Erlebe Bersuit live im Es Gremi auf ihrer \u201c25 Jahre mit Spanien\u201d-Tour und feiere Musik, Geschichte und eine einzigartige kulturelle Verbindung.","breadcrumb":{"@id":"https:\/\/visitpalma.com\/de\/event\/bersuit\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/visitpalma.com\/de\/event\/bersuit\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/visitpalma.com\/de\/event\/bersuit\/#primaryimage","url":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/08\/Bersuit-Palma-20251.jpg","contentUrl":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/08\/Bersuit-Palma-20251.jpg","width":960,"height":640,"caption":"Bersuit-Palma-2025"},{"@type":"BreadcrumbList","@id":"https:\/\/visitpalma.com\/de\/event\/bersuit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/visitpalma.com\/de\/"},{"@type":"ListItem","position":2,"name":"Veranstaltungen","item":"https:\/\/visitpalma.com\/de\/events\/"},{"@type":"ListItem","position":3,"name":"Bersuit"}]},{"@type":"WebSite","@id":"https:\/\/visitpalma.com\/de\/#website","url":"https:\/\/visitpalma.com\/de\/","name":"Visit Palma","description":"","publisher":{"@id":"https:\/\/visitpalma.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/visitpalma.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/visitpalma.com\/de\/#organization","name":"Fundaci\u00f3n Turismo Palma de Mallorca 365","url":"https:\/\/visitpalma.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/visitpalma.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/05\/Logo-Passion-for-Palma-de-Mallorca.svg","contentUrl":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/05\/Logo-Passion-for-Palma-de-Mallorca.svg","width":377,"height":377,"caption":"Fundaci\u00f3n Turismo Palma de Mallorca 365"},"image":{"@id":"https:\/\/visitpalma.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/passionforpalma","https:\/\/x.com\/passionforpalma","https:\/\/www.instagram.com\/passionforpalma_\/","https:\/\/www.youtube.com\/channel\/UCALF2N1FRnmAZYBttkQjedA"]}]}},"_links":{"self":[{"href":"https:\/\/visitpalma.com\/de\/wp-json\/wp\/v2\/tribe_events\/15880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visitpalma.com\/de\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/visitpalma.com\/de\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/visitpalma.com\/de\/wp-json\/wp\/v2\/users\/4"}],"version-history":[{"count":0,"href":"https:\/\/visitpalma.com\/de\/wp-json\/wp\/v2\/tribe_events\/15880\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visitpalma.com\/de\/wp-json\/wp\/v2\/media\/15876"}],"wp:attachment":[{"href":"https:\/\/visitpalma.com\/de\/wp-json\/wp\/v2\/media?parent=15880"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visitpalma.com\/de\/wp-json\/wp\/v2\/tags?post=15880"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/visitpalma.com\/de\/wp-json\/wp\/v2\/tribe_events_cat?post=15880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}