{"id":15689,"date":"2025-08-05T11:33:15","date_gmt":"2025-08-05T09:33:15","guid":{"rendered":"https:\/\/visitpalma.com\/event\/loneliness\/"},"modified":"2025-08-05T11:33:15","modified_gmt":"2025-08-05T09:33:15","slug":"loneliness","status":"publish","type":"tribe_events","link":"https:\/\/visitpalma.com\/de\/event\/loneliness\/","title":{"rendered":"Loneliness"},"content":{"rendered":"<p data-start=\"214\" data-end=\"364\">Tanz und Videokunst als kraftvoller Aufruf gegen Gewalt unter Jugendlichen. <\/p>\n<p data-start=\"366\" data-end=\"729\">Ein Max-Preis-nominiertes St\u00fcck \u00fcber Mobbing und das Schweigen der Gesellschaft.  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tanz und Videokunst als kraftvoller Aufruf gegen Gewalt unter Jugendlichen. Ein Max-Preis-nominiertes St\u00fcck \u00fcber Mobbing und das Schweigen der Gesellschaft.<\/p>\n","protected":false},"author":4,"featured_media":15685,"template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[171],"class_list":["post-15689","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-musik-und-tanz","cat_musik-und-tanz"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Loneliness: Tanz und Videokunst gegen Jugend\u2011Mobbing<\/title>\n<meta name=\"description\" content=\"B\u00fchnenst\u00fcck von Roberto G. Alonso, das mittels Tanz und Videokunst Gewalt unter Jugendlichen anprangert. Eine kraftvolle Auseinandersetzung mit Bullying.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/visitpalma.com\/de\/event\/loneliness\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Loneliness: Tanz und Videokunst gegen Jugend\u2011Mobbing\" \/>\n<meta property=\"og:description\" content=\"B\u00fchnenst\u00fcck von Roberto G. Alonso, das mittels Tanz und Videokunst Gewalt unter Jugendlichen anprangert. Eine kraftvolle Auseinandersetzung mit Bullying.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/visitpalma.com\/de\/event\/loneliness\/\" \/>\n<meta property=\"og:site_name\" content=\"Visit Palma\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/passionforpalma\" \/>\n<meta property=\"og:image\" content=\"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/08\/loneliness-palma-20251.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1140\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@passionforpalma\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/event\\\/loneliness\\\/\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/event\\\/loneliness\\\/\",\"name\":\"Loneliness: Tanz und Videokunst gegen Jugend\u2011Mobbing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/event\\\/loneliness\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/event\\\/loneliness\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/loneliness-palma-20251.jpg\",\"datePublished\":\"2025-08-05T09:33:15+00:00\",\"description\":\"B\u00fchnenst\u00fcck von Roberto G. Alonso, das mittels Tanz und Videokunst Gewalt unter Jugendlichen anprangert. Eine kraftvolle Auseinandersetzung mit Bullying.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/event\\\/loneliness\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/visitpalma.com\\\/de\\\/event\\\/loneliness\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/event\\\/loneliness\\\/#primaryimage\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/loneliness-palma-20251.jpg\",\"contentUrl\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/loneliness-palma-20251.jpg\",\"width\":1140,\"height\":600,\"caption\":\"loneliness-palma-2025\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/event\\\/loneliness\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veranstaltungen\",\"item\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Loneliness\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/\",\"name\":\"Visit Palma\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/#organization\",\"name\":\"Fundaci\u00f3n Turismo Palma de Mallorca 365\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Logo-Passion-for-Palma-de-Mallorca.svg\",\"contentUrl\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Logo-Passion-for-Palma-de-Mallorca.svg\",\"width\":377,\"height\":377,\"caption\":\"Fundaci\u00f3n Turismo Palma de Mallorca 365\"},\"image\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/passionforpalma\",\"https:\\\/\\\/x.com\\\/passionforpalma\",\"https:\\\/\\\/www.instagram.com\\\/passionforpalma_\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCALF2N1FRnmAZYBttkQjedA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Loneliness: Tanz und Videokunst gegen Jugend\u2011Mobbing","description":"B\u00fchnenst\u00fcck von Roberto G. Alonso, das mittels Tanz und Videokunst Gewalt unter Jugendlichen anprangert. Eine kraftvolle Auseinandersetzung mit Bullying.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/visitpalma.com\/de\/event\/loneliness\/","og_locale":"de_DE","og_type":"article","og_title":"Loneliness: Tanz und Videokunst gegen Jugend\u2011Mobbing","og_description":"B\u00fchnenst\u00fcck von Roberto G. Alonso, das mittels Tanz und Videokunst Gewalt unter Jugendlichen anprangert. Eine kraftvolle Auseinandersetzung mit Bullying.","og_url":"https:\/\/visitpalma.com\/de\/event\/loneliness\/","og_site_name":"Visit Palma","article_publisher":"https:\/\/www.facebook.com\/passionforpalma","og_image":[{"width":1140,"height":600,"url":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/08\/loneliness-palma-20251.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@passionforpalma","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/visitpalma.com\/de\/event\/loneliness\/","url":"https:\/\/visitpalma.com\/de\/event\/loneliness\/","name":"Loneliness: Tanz und Videokunst gegen Jugend\u2011Mobbing","isPartOf":{"@id":"https:\/\/visitpalma.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/visitpalma.com\/de\/event\/loneliness\/#primaryimage"},"image":{"@id":"https:\/\/visitpalma.com\/de\/event\/loneliness\/#primaryimage"},"thumbnailUrl":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/08\/loneliness-palma-20251.jpg","datePublished":"2025-08-05T09:33:15+00:00","description":"B\u00fchnenst\u00fcck von Roberto G. Alonso, das mittels Tanz und Videokunst Gewalt unter Jugendlichen anprangert. Eine kraftvolle Auseinandersetzung mit Bullying.","breadcrumb":{"@id":"https:\/\/visitpalma.com\/de\/event\/loneliness\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/visitpalma.com\/de\/event\/loneliness\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/visitpalma.com\/de\/event\/loneliness\/#primaryimage","url":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/08\/loneliness-palma-20251.jpg","contentUrl":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/08\/loneliness-palma-20251.jpg","width":1140,"height":600,"caption":"loneliness-palma-2025"},{"@type":"BreadcrumbList","@id":"https:\/\/visitpalma.com\/de\/event\/loneliness\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/visitpalma.com\/de\/"},{"@type":"ListItem","position":2,"name":"Veranstaltungen","item":"https:\/\/visitpalma.com\/de\/events\/"},{"@type":"ListItem","position":3,"name":"Loneliness"}]},{"@type":"WebSite","@id":"https:\/\/visitpalma.com\/de\/#website","url":"https:\/\/visitpalma.com\/de\/","name":"Visit Palma","description":"","publisher":{"@id":"https:\/\/visitpalma.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/visitpalma.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/visitpalma.com\/de\/#organization","name":"Fundaci\u00f3n Turismo Palma de Mallorca 365","url":"https:\/\/visitpalma.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/visitpalma.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/05\/Logo-Passion-for-Palma-de-Mallorca.svg","contentUrl":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/05\/Logo-Passion-for-Palma-de-Mallorca.svg","width":377,"height":377,"caption":"Fundaci\u00f3n Turismo Palma de Mallorca 365"},"image":{"@id":"https:\/\/visitpalma.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/passionforpalma","https:\/\/x.com\/passionforpalma","https:\/\/www.instagram.com\/passionforpalma_\/","https:\/\/www.youtube.com\/channel\/UCALF2N1FRnmAZYBttkQjedA"]}]}},"_links":{"self":[{"href":"https:\/\/visitpalma.com\/de\/wp-json\/wp\/v2\/tribe_events\/15689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visitpalma.com\/de\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/visitpalma.com\/de\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/visitpalma.com\/de\/wp-json\/wp\/v2\/users\/4"}],"version-history":[{"count":0,"href":"https:\/\/visitpalma.com\/de\/wp-json\/wp\/v2\/tribe_events\/15689\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visitpalma.com\/de\/wp-json\/wp\/v2\/media\/15685"}],"wp:attachment":[{"href":"https:\/\/visitpalma.com\/de\/wp-json\/wp\/v2\/media?parent=15689"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visitpalma.com\/de\/wp-json\/wp\/v2\/tags?post=15689"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/visitpalma.com\/de\/wp-json\/wp\/v2\/tribe_events_cat?post=15689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}