{"id":18580,"date":"2025-11-14T09:36:38","date_gmt":"2025-11-14T08:36:38","guid":{"rendered":"https:\/\/visitpalma.com\/event\/lucia-servera-en-concert\/"},"modified":"2025-11-14T09:36:38","modified_gmt":"2025-11-14T08:36:38","slug":"lucia-servera-en-concert","status":"publish","type":"tribe_events","link":"https:\/\/visitpalma.com\/ca\/event\/lucia-servera-en-concert\/","title":{"rendered":"Lucia Servera en concert"},"content":{"rendered":"<div>Amb 17 anys, Luc\u00eda Servera presenta el seu primer disc en un concert \u00edntim i senzill.<\/div>\n<div>Acompanyada pel seu pare i el seu germ\u00e0, ens convida a un viatge sonor d\u2019indie ac\u00fastic i sincer en un escenari transformat en el sal\u00f3 de la padrina.<\/div>\n<div><\/div>\n<div>Una vetlada en la qual cada can\u00e7\u00f3 pret\u00e9n ser un rac\u00f3 on quedar.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Amb 17 anys, Luc\u00eda Servera presenta el seu primer disc en un concert \u00edntim i senzill. Acompanyada pel seu pare i el seu germ\u00e0, ens convida a un viatge sonor [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":18579,"template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[169],"class_list":["post-18580","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-musica-dansa","cat_musica-dansa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Luc\u00eda Servera en concert \u2013 4 desembre 2025<\/title>\n<meta name=\"description\" content=\"Amb 17 anys, Luc\u00eda Servera presenta el seu primer disc en un concert \u00edntim al Teatre Municipal Xesc Forteza (Palma). Entrades disponibles.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/visitpalma.com\/ca\/event\/lucia-servera-en-concert\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Luc\u00eda Servera en concert \u2013 4 desembre 2025\" \/>\n<meta property=\"og:description\" content=\"Amb 17 anys, Luc\u00eda Servera presenta el seu primer disc en un concert \u00edntim al Teatre Municipal Xesc Forteza (Palma). Entrades disponibles.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/visitpalma.com\/ca\/event\/lucia-servera-en-concert\/\" \/>\n<meta property=\"og:site_name\" content=\"Visit Palma\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/passionforpalma\" \/>\n<meta property=\"og:image\" content=\"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/11\/Lucia-Servera.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"812\" \/>\n\t<meta property=\"og:image:height\" content=\"609\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@passionforpalma\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/event\\\/lucia-servera-en-concert\\\/\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/event\\\/lucia-servera-en-concert\\\/\",\"name\":\"Luc\u00eda Servera en concert \u2013 4 desembre 2025\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/event\\\/lucia-servera-en-concert\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/event\\\/lucia-servera-en-concert\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Lucia-Servera.jpg\",\"datePublished\":\"2025-11-14T08:36:38+00:00\",\"description\":\"Amb 17 anys, Luc\u00eda Servera presenta el seu primer disc en un concert \u00edntim al Teatre Municipal Xesc Forteza (Palma). Entrades disponibles.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/event\\\/lucia-servera-en-concert\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/visitpalma.com\\\/ca\\\/event\\\/lucia-servera-en-concert\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/event\\\/lucia-servera-en-concert\\\/#primaryimage\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Lucia-Servera.jpg\",\"contentUrl\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Lucia-Servera.jpg\",\"width\":812,\"height\":609,\"caption\":\"Lucia Servera en concert\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/event\\\/lucia-servera-en-concert\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Esdeveniments\",\"item\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lucia Servera en concert\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/\",\"name\":\"Visit Palma\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/#organization\",\"name\":\"Fundaci\u00f3n Turismo Palma de Mallorca 365\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Logo-Passion-for-Palma-de-Mallorca.svg\",\"contentUrl\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Logo-Passion-for-Palma-de-Mallorca.svg\",\"width\":377,\"height\":377,\"caption\":\"Fundaci\u00f3n Turismo Palma de Mallorca 365\"},\"image\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/passionforpalma\",\"https:\\\/\\\/x.com\\\/passionforpalma\",\"https:\\\/\\\/www.instagram.com\\\/passionforpalma_\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCALF2N1FRnmAZYBttkQjedA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Luc\u00eda Servera en concert \u2013 4 desembre 2025","description":"Amb 17 anys, Luc\u00eda Servera presenta el seu primer disc en un concert \u00edntim al Teatre Municipal Xesc Forteza (Palma). Entrades disponibles.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/visitpalma.com\/ca\/event\/lucia-servera-en-concert\/","og_locale":"ca_ES","og_type":"article","og_title":"Luc\u00eda Servera en concert \u2013 4 desembre 2025","og_description":"Amb 17 anys, Luc\u00eda Servera presenta el seu primer disc en un concert \u00edntim al Teatre Municipal Xesc Forteza (Palma). Entrades disponibles.","og_url":"https:\/\/visitpalma.com\/ca\/event\/lucia-servera-en-concert\/","og_site_name":"Visit Palma","article_publisher":"https:\/\/www.facebook.com\/passionforpalma","og_image":[{"width":812,"height":609,"url":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/11\/Lucia-Servera.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@passionforpalma","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/visitpalma.com\/ca\/event\/lucia-servera-en-concert\/","url":"https:\/\/visitpalma.com\/ca\/event\/lucia-servera-en-concert\/","name":"Luc\u00eda Servera en concert \u2013 4 desembre 2025","isPartOf":{"@id":"https:\/\/visitpalma.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/visitpalma.com\/ca\/event\/lucia-servera-en-concert\/#primaryimage"},"image":{"@id":"https:\/\/visitpalma.com\/ca\/event\/lucia-servera-en-concert\/#primaryimage"},"thumbnailUrl":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/11\/Lucia-Servera.jpg","datePublished":"2025-11-14T08:36:38+00:00","description":"Amb 17 anys, Luc\u00eda Servera presenta el seu primer disc en un concert \u00edntim al Teatre Municipal Xesc Forteza (Palma). Entrades disponibles.","breadcrumb":{"@id":"https:\/\/visitpalma.com\/ca\/event\/lucia-servera-en-concert\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/visitpalma.com\/ca\/event\/lucia-servera-en-concert\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/visitpalma.com\/ca\/event\/lucia-servera-en-concert\/#primaryimage","url":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/11\/Lucia-Servera.jpg","contentUrl":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/11\/Lucia-Servera.jpg","width":812,"height":609,"caption":"Lucia Servera en concert"},{"@type":"BreadcrumbList","@id":"https:\/\/visitpalma.com\/ca\/event\/lucia-servera-en-concert\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/visitpalma.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Esdeveniments","item":"https:\/\/visitpalma.com\/ca\/events\/"},{"@type":"ListItem","position":3,"name":"Lucia Servera en concert"}]},{"@type":"WebSite","@id":"https:\/\/visitpalma.com\/ca\/#website","url":"https:\/\/visitpalma.com\/ca\/","name":"Visit Palma","description":"","publisher":{"@id":"https:\/\/visitpalma.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/visitpalma.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/visitpalma.com\/ca\/#organization","name":"Fundaci\u00f3n Turismo Palma de Mallorca 365","url":"https:\/\/visitpalma.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/visitpalma.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/05\/Logo-Passion-for-Palma-de-Mallorca.svg","contentUrl":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/05\/Logo-Passion-for-Palma-de-Mallorca.svg","width":377,"height":377,"caption":"Fundaci\u00f3n Turismo Palma de Mallorca 365"},"image":{"@id":"https:\/\/visitpalma.com\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/passionforpalma","https:\/\/x.com\/passionforpalma","https:\/\/www.instagram.com\/passionforpalma_\/","https:\/\/www.youtube.com\/channel\/UCALF2N1FRnmAZYBttkQjedA"]}]}},"_links":{"self":[{"href":"https:\/\/visitpalma.com\/ca\/wp-json\/wp\/v2\/tribe_events\/18580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visitpalma.com\/ca\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/visitpalma.com\/ca\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/visitpalma.com\/ca\/wp-json\/wp\/v2\/users\/4"}],"version-history":[{"count":0,"href":"https:\/\/visitpalma.com\/ca\/wp-json\/wp\/v2\/tribe_events\/18580\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visitpalma.com\/ca\/wp-json\/wp\/v2\/media\/18579"}],"wp:attachment":[{"href":"https:\/\/visitpalma.com\/ca\/wp-json\/wp\/v2\/media?parent=18580"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visitpalma.com\/ca\/wp-json\/wp\/v2\/tags?post=18580"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/visitpalma.com\/ca\/wp-json\/wp\/v2\/tribe_events_cat?post=18580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}