{"id":16409,"date":"2025-09-15T10:40:35","date_gmt":"2025-09-15T08:40:35","guid":{"rendered":"https:\/\/visitpalma.com\/event\/coll-un-gigante-en-el-tbo\/"},"modified":"2025-09-15T10:40:35","modified_gmt":"2025-09-15T08:40:35","slug":"coll-un-gigante-en-el-tbo","status":"publish","type":"tribe_events","link":"https:\/\/visitpalma.com\/ca\/event\/coll-un-gigante-en-el-tbo\/","title":{"rendered":"Coll, un gigante en el TBO"},"content":{"rendered":"<p>El Casal Solleric i el Cl\u00faster de C\u00f2mic i Nous M\u00e8dia de Mallorca presenten la mostra m\u00e9s gran dedicada a Josep Coll (Barcelona, 1924-1984), un dels grans dibuixants d\u2019historietes del segle XX i figura clau del m\u00edtic TBO. L\u2019exposici\u00f3 convida a redescobrir el seu estil modern, l\u2019humor fi i els seus personatges inesborrables, des de n\u00e0ufrags i ca\u00e7adors fins a can\u00edbals i conductors sorpresos en situacions enginyoses. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Casal Solleric i el Cl\u00faster de C\u00f2mic i Nous M\u00e8dia de Mallorca presenten la mostra m\u00e9s gran dedicada a Josep Coll (Barcelona, 1924-1984), un dels grans dibuixants d\u2019historietes del [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":16405,"template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[181],"class_list":["post-16409","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-exposicions","cat_exposicions"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Josep Coll al Casal Solleric, gran mostra de c\u00f2mic<\/title>\n<meta name=\"description\" content=\"El Casal Solleric acull la major exposici\u00f3 de Josep Coll, mestre del TBO i figura clau del c\u00f2mic espanyol del segle XX.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/visitpalma.com\/ca\/event\/coll-un-gigante-en-el-tbo\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Josep Coll al Casal Solleric, gran mostra de c\u00f2mic\" \/>\n<meta property=\"og:description\" content=\"El Casal Solleric acull la major exposici\u00f3 de Josep Coll, mestre del TBO i figura clau del c\u00f2mic espanyol del segle XX.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/visitpalma.com\/ca\/event\/coll-un-gigante-en-el-tbo\/\" \/>\n<meta property=\"og:site_name\" content=\"Visit Palma\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/passionforpalma\" \/>\n<meta property=\"og:image\" content=\"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/09\/Coll-Casal-Solleric-Palma.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@passionforpalma\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/event\\\/coll-un-gigante-en-el-tbo\\\/\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/event\\\/coll-un-gigante-en-el-tbo\\\/\",\"name\":\"Josep Coll al Casal Solleric, gran mostra de c\u00f2mic\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/event\\\/coll-un-gigante-en-el-tbo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/event\\\/coll-un-gigante-en-el-tbo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Coll-Casal-Solleric-Palma.jpg\",\"datePublished\":\"2025-09-15T08:40:35+00:00\",\"description\":\"El Casal Solleric acull la major exposici\u00f3 de Josep Coll, mestre del TBO i figura clau del c\u00f2mic espanyol del segle XX.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/event\\\/coll-un-gigante-en-el-tbo\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/visitpalma.com\\\/ca\\\/event\\\/coll-un-gigante-en-el-tbo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/event\\\/coll-un-gigante-en-el-tbo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Coll-Casal-Solleric-Palma.jpg\",\"contentUrl\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Coll-Casal-Solleric-Palma.jpg\",\"width\":1080,\"height\":1350,\"caption\":\"Coll Casal Solleric Palma\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/event\\\/coll-un-gigante-en-el-tbo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Esdeveniments\",\"item\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Coll, un gigante en el TBO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/\",\"name\":\"Visit Palma\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/#organization\",\"name\":\"Fundaci\u00f3n Turismo Palma de Mallorca 365\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Logo-Passion-for-Palma-de-Mallorca.svg\",\"contentUrl\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Logo-Passion-for-Palma-de-Mallorca.svg\",\"width\":377,\"height\":377,\"caption\":\"Fundaci\u00f3n Turismo Palma de Mallorca 365\"},\"image\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/passionforpalma\",\"https:\\\/\\\/x.com\\\/passionforpalma\",\"https:\\\/\\\/www.instagram.com\\\/passionforpalma_\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCALF2N1FRnmAZYBttkQjedA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Josep Coll al Casal Solleric, gran mostra de c\u00f2mic","description":"El Casal Solleric acull la major exposici\u00f3 de Josep Coll, mestre del TBO i figura clau del c\u00f2mic espanyol del segle XX.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/visitpalma.com\/ca\/event\/coll-un-gigante-en-el-tbo\/","og_locale":"ca_ES","og_type":"article","og_title":"Josep Coll al Casal Solleric, gran mostra de c\u00f2mic","og_description":"El Casal Solleric acull la major exposici\u00f3 de Josep Coll, mestre del TBO i figura clau del c\u00f2mic espanyol del segle XX.","og_url":"https:\/\/visitpalma.com\/ca\/event\/coll-un-gigante-en-el-tbo\/","og_site_name":"Visit Palma","article_publisher":"https:\/\/www.facebook.com\/passionforpalma","og_image":[{"width":1080,"height":1350,"url":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/09\/Coll-Casal-Solleric-Palma.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@passionforpalma","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/visitpalma.com\/ca\/event\/coll-un-gigante-en-el-tbo\/","url":"https:\/\/visitpalma.com\/ca\/event\/coll-un-gigante-en-el-tbo\/","name":"Josep Coll al Casal Solleric, gran mostra de c\u00f2mic","isPartOf":{"@id":"https:\/\/visitpalma.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/visitpalma.com\/ca\/event\/coll-un-gigante-en-el-tbo\/#primaryimage"},"image":{"@id":"https:\/\/visitpalma.com\/ca\/event\/coll-un-gigante-en-el-tbo\/#primaryimage"},"thumbnailUrl":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/09\/Coll-Casal-Solleric-Palma.jpg","datePublished":"2025-09-15T08:40:35+00:00","description":"El Casal Solleric acull la major exposici\u00f3 de Josep Coll, mestre del TBO i figura clau del c\u00f2mic espanyol del segle XX.","breadcrumb":{"@id":"https:\/\/visitpalma.com\/ca\/event\/coll-un-gigante-en-el-tbo\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/visitpalma.com\/ca\/event\/coll-un-gigante-en-el-tbo\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/visitpalma.com\/ca\/event\/coll-un-gigante-en-el-tbo\/#primaryimage","url":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/09\/Coll-Casal-Solleric-Palma.jpg","contentUrl":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/09\/Coll-Casal-Solleric-Palma.jpg","width":1080,"height":1350,"caption":"Coll Casal Solleric Palma"},{"@type":"BreadcrumbList","@id":"https:\/\/visitpalma.com\/ca\/event\/coll-un-gigante-en-el-tbo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/visitpalma.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Esdeveniments","item":"https:\/\/visitpalma.com\/ca\/events\/"},{"@type":"ListItem","position":3,"name":"Coll, un gigante en el TBO"}]},{"@type":"WebSite","@id":"https:\/\/visitpalma.com\/ca\/#website","url":"https:\/\/visitpalma.com\/ca\/","name":"Visit Palma","description":"","publisher":{"@id":"https:\/\/visitpalma.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/visitpalma.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/visitpalma.com\/ca\/#organization","name":"Fundaci\u00f3n Turismo Palma de Mallorca 365","url":"https:\/\/visitpalma.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/visitpalma.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/05\/Logo-Passion-for-Palma-de-Mallorca.svg","contentUrl":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/05\/Logo-Passion-for-Palma-de-Mallorca.svg","width":377,"height":377,"caption":"Fundaci\u00f3n Turismo Palma de Mallorca 365"},"image":{"@id":"https:\/\/visitpalma.com\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/passionforpalma","https:\/\/x.com\/passionforpalma","https:\/\/www.instagram.com\/passionforpalma_\/","https:\/\/www.youtube.com\/channel\/UCALF2N1FRnmAZYBttkQjedA"]}]}},"_links":{"self":[{"href":"https:\/\/visitpalma.com\/ca\/wp-json\/wp\/v2\/tribe_events\/16409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visitpalma.com\/ca\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/visitpalma.com\/ca\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/visitpalma.com\/ca\/wp-json\/wp\/v2\/users\/4"}],"version-history":[{"count":0,"href":"https:\/\/visitpalma.com\/ca\/wp-json\/wp\/v2\/tribe_events\/16409\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visitpalma.com\/ca\/wp-json\/wp\/v2\/media\/16405"}],"wp:attachment":[{"href":"https:\/\/visitpalma.com\/ca\/wp-json\/wp\/v2\/media?parent=16409"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visitpalma.com\/ca\/wp-json\/wp\/v2\/tags?post=16409"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/visitpalma.com\/ca\/wp-json\/wp\/v2\/tribe_events_cat?post=16409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}