{"id":15887,"date":"2025-08-11T10:48:39","date_gmt":"2025-08-11T08:48:39","guid":{"rendered":"https:\/\/visitpalma.com\/event\/compota-de-manana\/"},"modified":"2025-08-11T10:48:39","modified_gmt":"2025-08-11T08:48:39","slug":"compota-de-manana","status":"publish","type":"tribe_events","link":"https:\/\/visitpalma.com\/ca\/event\/compota-de-manana\/","title":{"rendered":"Compota de Manana"},"content":{"rendered":"<p>La banda m\u00e9s innovadora i atrevida de l\u2019escena llatina europea, COMPOTA DE MANANA, arriba a Mallorca per presentar el seu nou disc <em data-start=\"247\" data-end=\"267\">Cuesti\u00f3n de Tiempo<\/em>. Liderats per Erik Castillo, cantant i percussionista, ofereixen una proposta \u00fanica que barreja salsa, timba, rap i visuals, creant un espectacle vibrant i ple d\u2019energia. Despr\u00e9s de participar en festivals importants com Color Caf\u00e9 a B\u00e8lgica o FIC a Orange, i escenaris emblem\u00e0tics com Apolo o Sala Paloma, arriben a Es Gremi amb un concert que trenca amb la salsa tradicional i conquereix amb ritme urb\u00e0, creativitat sense l\u00edmits i aut\u00e8ntic sabor llat\u00ed. Si pensaves que ja havies viscut el millor de la salsa, prepara\u2019t per una experi\u00e8ncia completament nova.   <\/p>\n","protected":false},"excerpt":{"rendered":"<p>La banda m\u00e9s innovadora i atrevida de l\u2019escena llatina europea, COMPOTA DE MANANA, arriba a Mallorca per presentar el seu nou disc Cuesti\u00f3n de Tiempo. Liderats per Erik Castillo, cantant [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":15883,"template":"","meta":{"_monsterinsights_skip_tracking":false,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[169],"class_list":["post-15887","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-musica-dansa","cat_musica-dansa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Compota de Manana a Es Gremi \u2013 Salsa i ritme explosiu<\/title>\n<meta name=\"description\" content=\"Gaudeix a Es Gremi de l\u2019energia \u00fanica de Compota de Manana, que combina salsa, rap i timba amb un directe vibrant i creatiu.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/visitpalma.com\/ca\/event\/compota-de-manana\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Compota de Manana a Es Gremi \u2013 Salsa i ritme explosiu\" \/>\n<meta property=\"og:description\" content=\"Gaudeix a Es Gremi de l\u2019energia \u00fanica de Compota de Manana, que combina salsa, rap i timba amb un directe vibrant i creatiu.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/visitpalma.com\/ca\/event\/compota-de-manana\/\" \/>\n<meta property=\"og:site_name\" content=\"Visit Palma\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/passionforpalma\" \/>\n<meta property=\"og:image\" content=\"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/08\/Compota-Manana-Palma-20251.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@passionforpalma\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/event\\\/compota-de-manana\\\/\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/event\\\/compota-de-manana\\\/\",\"name\":\"Compota de Manana a Es Gremi \u2013 Salsa i ritme explosiu\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/event\\\/compota-de-manana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/event\\\/compota-de-manana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Compota-Manana-Palma-20251.jpg\",\"datePublished\":\"2025-08-11T08:48:39+00:00\",\"description\":\"Gaudeix a Es Gremi de l\u2019energia \u00fanica de Compota de Manana, que combina salsa, rap i timba amb un directe vibrant i creatiu.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/event\\\/compota-de-manana\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/visitpalma.com\\\/ca\\\/event\\\/compota-de-manana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/event\\\/compota-de-manana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Compota-Manana-Palma-20251.jpg\",\"contentUrl\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Compota-Manana-Palma-20251.jpg\",\"width\":960,\"height\":640,\"caption\":\"Compota-Manana-Palma-2025\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/event\\\/compota-de-manana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Esdeveniments\",\"item\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Compota de Manana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/\",\"name\":\"Visit Palma\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/#organization\",\"name\":\"Fundaci\u00f3n Turismo Palma de Mallorca 365\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Logo-Passion-for-Palma-de-Mallorca.svg\",\"contentUrl\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Logo-Passion-for-Palma-de-Mallorca.svg\",\"width\":377,\"height\":377,\"caption\":\"Fundaci\u00f3n Turismo Palma de Mallorca 365\"},\"image\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/passionforpalma\",\"https:\\\/\\\/x.com\\\/passionforpalma\",\"https:\\\/\\\/www.instagram.com\\\/passionforpalma_\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCALF2N1FRnmAZYBttkQjedA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Compota de Manana a Es Gremi \u2013 Salsa i ritme explosiu","description":"Gaudeix a Es Gremi de l\u2019energia \u00fanica de Compota de Manana, que combina salsa, rap i timba amb un directe vibrant i creatiu.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/visitpalma.com\/ca\/event\/compota-de-manana\/","og_locale":"ca_ES","og_type":"article","og_title":"Compota de Manana a Es Gremi \u2013 Salsa i ritme explosiu","og_description":"Gaudeix a Es Gremi de l\u2019energia \u00fanica de Compota de Manana, que combina salsa, rap i timba amb un directe vibrant i creatiu.","og_url":"https:\/\/visitpalma.com\/ca\/event\/compota-de-manana\/","og_site_name":"Visit Palma","article_publisher":"https:\/\/www.facebook.com\/passionforpalma","og_image":[{"width":960,"height":640,"url":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/08\/Compota-Manana-Palma-20251.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@passionforpalma","twitter_misc":{"Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/visitpalma.com\/ca\/event\/compota-de-manana\/","url":"https:\/\/visitpalma.com\/ca\/event\/compota-de-manana\/","name":"Compota de Manana a Es Gremi \u2013 Salsa i ritme explosiu","isPartOf":{"@id":"https:\/\/visitpalma.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/visitpalma.com\/ca\/event\/compota-de-manana\/#primaryimage"},"image":{"@id":"https:\/\/visitpalma.com\/ca\/event\/compota-de-manana\/#primaryimage"},"thumbnailUrl":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/08\/Compota-Manana-Palma-20251.jpg","datePublished":"2025-08-11T08:48:39+00:00","description":"Gaudeix a Es Gremi de l\u2019energia \u00fanica de Compota de Manana, que combina salsa, rap i timba amb un directe vibrant i creatiu.","breadcrumb":{"@id":"https:\/\/visitpalma.com\/ca\/event\/compota-de-manana\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/visitpalma.com\/ca\/event\/compota-de-manana\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/visitpalma.com\/ca\/event\/compota-de-manana\/#primaryimage","url":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/08\/Compota-Manana-Palma-20251.jpg","contentUrl":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/08\/Compota-Manana-Palma-20251.jpg","width":960,"height":640,"caption":"Compota-Manana-Palma-2025"},{"@type":"BreadcrumbList","@id":"https:\/\/visitpalma.com\/ca\/event\/compota-de-manana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/visitpalma.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Esdeveniments","item":"https:\/\/visitpalma.com\/ca\/events\/"},{"@type":"ListItem","position":3,"name":"Compota de Manana"}]},{"@type":"WebSite","@id":"https:\/\/visitpalma.com\/ca\/#website","url":"https:\/\/visitpalma.com\/ca\/","name":"Visit Palma","description":"","publisher":{"@id":"https:\/\/visitpalma.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/visitpalma.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/visitpalma.com\/ca\/#organization","name":"Fundaci\u00f3n Turismo Palma de Mallorca 365","url":"https:\/\/visitpalma.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/visitpalma.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/05\/Logo-Passion-for-Palma-de-Mallorca.svg","contentUrl":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/05\/Logo-Passion-for-Palma-de-Mallorca.svg","width":377,"height":377,"caption":"Fundaci\u00f3n Turismo Palma de Mallorca 365"},"image":{"@id":"https:\/\/visitpalma.com\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/passionforpalma","https:\/\/x.com\/passionforpalma","https:\/\/www.instagram.com\/passionforpalma_\/","https:\/\/www.youtube.com\/channel\/UCALF2N1FRnmAZYBttkQjedA"]}]}},"_links":{"self":[{"href":"https:\/\/visitpalma.com\/ca\/wp-json\/wp\/v2\/tribe_events\/15887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visitpalma.com\/ca\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/visitpalma.com\/ca\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/visitpalma.com\/ca\/wp-json\/wp\/v2\/users\/4"}],"version-history":[{"count":0,"href":"https:\/\/visitpalma.com\/ca\/wp-json\/wp\/v2\/tribe_events\/15887\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visitpalma.com\/ca\/wp-json\/wp\/v2\/media\/15883"}],"wp:attachment":[{"href":"https:\/\/visitpalma.com\/ca\/wp-json\/wp\/v2\/media?parent=15887"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visitpalma.com\/ca\/wp-json\/wp\/v2\/tags?post=15887"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/visitpalma.com\/ca\/wp-json\/wp\/v2\/tribe_events_cat?post=15887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}