{"id":15661,"date":"2025-08-05T11:13:57","date_gmt":"2025-08-05T09:13:57","guid":{"rendered":"https:\/\/visitpalma.com\/event\/la-magia-del-cine\/"},"modified":"2025-08-05T11:23:55","modified_gmt":"2025-08-05T09:23:55","slug":"la-magia-del-cine","status":"publish","type":"tribe_events","link":"https:\/\/visitpalma.com\/ca\/event\/la-magia-del-cine\/","title":{"rendered":"La magia del cine"},"content":{"rendered":"<p data-start=\"117\" data-end=\"191\">Un viatge musical apassionant per les bandes sonores m\u00e9s emblem\u00e0tiques del cinema.<\/p>\n<p data-start=\"193\" data-end=\"403\">L&#8217;Orquestra Simf\u00f2nica de les Illes Balears ofereix un concert que celebra la for\u00e7a emocional del cinema i la m\u00fasica, una uni\u00f3 capa\u00e7 de commoure i despertar records.<\/p>\n<p data-start=\"405\" data-end=\"643\">L\u2019esdeveniment comptar\u00e0 amb la pres\u00e8ncia destacada de Jos\u00e9 Luis Garci, primer director espanyol a guanyar un \u00d2scar, i el diplom\u00e0tic Inocencio Arias, que enriquiran l\u2019experi\u00e8ncia amb comentaris plens d\u2019an\u00e8cdotes i dades interessants. <\/p>\n<p data-start=\"645\" data-end=\"858\">El programa inclou composicions de grans noms del cinema com Williams, Mancini, Barry o Jarre, aix\u00ed com obres cl\u00e0ssiques de Brahms i Haendel que tamb\u00e9 han brillat en el cinema.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un viatge musical apassionant per les bandes sonores m\u00e9s emblem\u00e0tiques del cinema. L&#8217;Orquestra Simf\u00f2nica de les Illes Balears ofereix un concert que celebra la for\u00e7a emocional del cinema i la [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":15657,"template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[169],"class_list":["post-15661","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-musica-dansa","cat_musica-dansa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La m\u00e0gia del cine amb OSIB al Teatre Principal<\/title>\n<meta name=\"description\" content=\"Gaudeix d\u2019un concert comentat per Jos\u00e9 Luis Garci i Inocencio Arias al Teatre Principal. Un recorregut musical per les bandes sonores m\u00e9s emblem\u00e0tiques.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/visitpalma.com\/ca\/event\/la-magia-del-cine\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La m\u00e0gia del cine amb OSIB al Teatre Principal\" \/>\n<meta property=\"og:description\" content=\"Gaudeix d\u2019un concert comentat per Jos\u00e9 Luis Garci i Inocencio Arias al Teatre Principal. Un recorregut musical per les bandes sonores m\u00e9s emblem\u00e0tiques.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/visitpalma.com\/ca\/event\/la-magia-del-cine\/\" \/>\n<meta property=\"og:site_name\" content=\"Visit Palma\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/passionforpalma\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-05T09:23:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/08\/la-magia-del-cine-palma-20251.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1140\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@passionforpalma\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/event\\\/la-magia-del-cine\\\/\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/event\\\/la-magia-del-cine\\\/\",\"name\":\"La m\u00e0gia del cine amb OSIB al Teatre Principal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/event\\\/la-magia-del-cine\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/event\\\/la-magia-del-cine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/la-magia-del-cine-palma-20251.jpg\",\"datePublished\":\"2025-08-05T09:13:57+00:00\",\"dateModified\":\"2025-08-05T09:23:55+00:00\",\"description\":\"Gaudeix d\u2019un concert comentat per Jos\u00e9 Luis Garci i Inocencio Arias al Teatre Principal. Un recorregut musical per les bandes sonores m\u00e9s emblem\u00e0tiques.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/event\\\/la-magia-del-cine\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/visitpalma.com\\\/ca\\\/event\\\/la-magia-del-cine\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/event\\\/la-magia-del-cine\\\/#primaryimage\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/la-magia-del-cine-palma-20251.jpg\",\"contentUrl\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/la-magia-del-cine-palma-20251.jpg\",\"width\":1140,\"height\":600,\"caption\":\"la-magia-del-cine-palma-2025\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/event\\\/la-magia-del-cine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Esdeveniments\",\"item\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"La magia del cine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/\",\"name\":\"Visit Palma\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/#organization\",\"name\":\"Fundaci\u00f3n Turismo Palma de Mallorca 365\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Logo-Passion-for-Palma-de-Mallorca.svg\",\"contentUrl\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Logo-Passion-for-Palma-de-Mallorca.svg\",\"width\":377,\"height\":377,\"caption\":\"Fundaci\u00f3n Turismo Palma de Mallorca 365\"},\"image\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/passionforpalma\",\"https:\\\/\\\/x.com\\\/passionforpalma\",\"https:\\\/\\\/www.instagram.com\\\/passionforpalma_\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCALF2N1FRnmAZYBttkQjedA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La m\u00e0gia del cine amb OSIB al Teatre Principal","description":"Gaudeix d\u2019un concert comentat per Jos\u00e9 Luis Garci i Inocencio Arias al Teatre Principal. Un recorregut musical per les bandes sonores m\u00e9s emblem\u00e0tiques.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/visitpalma.com\/ca\/event\/la-magia-del-cine\/","og_locale":"ca_ES","og_type":"article","og_title":"La m\u00e0gia del cine amb OSIB al Teatre Principal","og_description":"Gaudeix d\u2019un concert comentat per Jos\u00e9 Luis Garci i Inocencio Arias al Teatre Principal. Un recorregut musical per les bandes sonores m\u00e9s emblem\u00e0tiques.","og_url":"https:\/\/visitpalma.com\/ca\/event\/la-magia-del-cine\/","og_site_name":"Visit Palma","article_publisher":"https:\/\/www.facebook.com\/passionforpalma","article_modified_time":"2025-08-05T09:23:55+00:00","og_image":[{"width":1140,"height":600,"url":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/08\/la-magia-del-cine-palma-20251.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@passionforpalma","twitter_misc":{"Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/visitpalma.com\/ca\/event\/la-magia-del-cine\/","url":"https:\/\/visitpalma.com\/ca\/event\/la-magia-del-cine\/","name":"La m\u00e0gia del cine amb OSIB al Teatre Principal","isPartOf":{"@id":"https:\/\/visitpalma.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/visitpalma.com\/ca\/event\/la-magia-del-cine\/#primaryimage"},"image":{"@id":"https:\/\/visitpalma.com\/ca\/event\/la-magia-del-cine\/#primaryimage"},"thumbnailUrl":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/08\/la-magia-del-cine-palma-20251.jpg","datePublished":"2025-08-05T09:13:57+00:00","dateModified":"2025-08-05T09:23:55+00:00","description":"Gaudeix d\u2019un concert comentat per Jos\u00e9 Luis Garci i Inocencio Arias al Teatre Principal. Un recorregut musical per les bandes sonores m\u00e9s emblem\u00e0tiques.","breadcrumb":{"@id":"https:\/\/visitpalma.com\/ca\/event\/la-magia-del-cine\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/visitpalma.com\/ca\/event\/la-magia-del-cine\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/visitpalma.com\/ca\/event\/la-magia-del-cine\/#primaryimage","url":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/08\/la-magia-del-cine-palma-20251.jpg","contentUrl":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/08\/la-magia-del-cine-palma-20251.jpg","width":1140,"height":600,"caption":"la-magia-del-cine-palma-2025"},{"@type":"BreadcrumbList","@id":"https:\/\/visitpalma.com\/ca\/event\/la-magia-del-cine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/visitpalma.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Esdeveniments","item":"https:\/\/visitpalma.com\/ca\/events\/"},{"@type":"ListItem","position":3,"name":"La magia del cine"}]},{"@type":"WebSite","@id":"https:\/\/visitpalma.com\/ca\/#website","url":"https:\/\/visitpalma.com\/ca\/","name":"Visit Palma","description":"","publisher":{"@id":"https:\/\/visitpalma.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/visitpalma.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/visitpalma.com\/ca\/#organization","name":"Fundaci\u00f3n Turismo Palma de Mallorca 365","url":"https:\/\/visitpalma.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/visitpalma.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/05\/Logo-Passion-for-Palma-de-Mallorca.svg","contentUrl":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/05\/Logo-Passion-for-Palma-de-Mallorca.svg","width":377,"height":377,"caption":"Fundaci\u00f3n Turismo Palma de Mallorca 365"},"image":{"@id":"https:\/\/visitpalma.com\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/passionforpalma","https:\/\/x.com\/passionforpalma","https:\/\/www.instagram.com\/passionforpalma_\/","https:\/\/www.youtube.com\/channel\/UCALF2N1FRnmAZYBttkQjedA"]}]}},"_links":{"self":[{"href":"https:\/\/visitpalma.com\/ca\/wp-json\/wp\/v2\/tribe_events\/15661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visitpalma.com\/ca\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/visitpalma.com\/ca\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/visitpalma.com\/ca\/wp-json\/wp\/v2\/users\/4"}],"version-history":[{"count":1,"href":"https:\/\/visitpalma.com\/ca\/wp-json\/wp\/v2\/tribe_events\/15661\/revisions"}],"predecessor-version":[{"id":15673,"href":"https:\/\/visitpalma.com\/ca\/wp-json\/wp\/v2\/tribe_events\/15661\/revisions\/15673"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visitpalma.com\/ca\/wp-json\/wp\/v2\/media\/15657"}],"wp:attachment":[{"href":"https:\/\/visitpalma.com\/ca\/wp-json\/wp\/v2\/media?parent=15661"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visitpalma.com\/ca\/wp-json\/wp\/v2\/tags?post=15661"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/visitpalma.com\/ca\/wp-json\/wp\/v2\/tribe_events_cat?post=15661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}