{"id":15505,"date":"2025-07-25T12:23:50","date_gmt":"2025-07-25T10:23:50","guid":{"rendered":"https:\/\/visitpalma.com\/event\/paysage-miro-el-color-i-la-seva-ombra\/"},"modified":"2025-07-25T12:23:50","modified_gmt":"2025-07-25T10:23:50","slug":"paysage-miro-el-color-i-la-seva-ombra","status":"publish","type":"tribe_events","link":"https:\/\/visitpalma.com\/ca\/event\/paysage-miro-el-color-i-la-seva-ombra\/","title":{"rendered":"Paysage Mir\u00f3: El color i la seva ombra"},"content":{"rendered":"<p data-start=\"241\" data-end=\"533\">L\u2019exposici\u00f3 <em data-start=\"255\" data-end=\"291\">Paysage Mir\u00f3. El color i la seva ombra <\/em> ens convida a explorar l\u2019univers art\u00edstic de Joan Mir\u00f3 mitjan\u00e7ant el di\u00e0leg entre la seva pintura i escultura. A trav\u00e9s d\u2019una selecci\u00f3 d\u2019obres \u2014escultures en bronze, pintures i treballs sobre paper\u2014 s\u2019ofereix una mirada no lineal al seu proc\u00e9s creatiu. <\/p>\n<p data-start=\"535\" data-end=\"864\">S\u2019hi destaca especialment l\u2019escultura produ\u00efda a partir dels anys seixanta, amb personatges de car\u00e0cter tot\u00e8mic i assemblatges elaborats a partir d\u2019objectes trobats, en una clara al\u00b7lusi\u00f3 a l\u2019art popular i primitiu. Aquestes peces conviuen amb pintures plenes d\u2019enigmes i simbologia ancestral. <\/p>\n<p data-start=\"866\" data-end=\"1175\">La mostra forma part del projecte <em data-start=\"907\" data-end=\"921\">Paysage Mir\u00f3<\/em>, una proposta compartida amb el Museu Reina Sof\u00eda i presentada en quatre espais de refer\u00e8ncia de l\u2019art contemporani a Palma: la Llotja, Es Baluard Museu, Fundaci\u00f3 Pilar i Joan Mir\u00f3 Mallorca i Casal Solleric. Cada instituci\u00f3 ofereix la seva pr\u00f2pia visi\u00f3 per construir un paisatge com\u00fa. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019exposici\u00f3 Paysage Mir\u00f3. El color i la seva ombra ens convida a explorar l\u2019univers art\u00edstic de Joan Mir\u00f3 mitjan\u00e7ant el di\u00e0leg entre la seva pintura i escultura. A trav\u00e9s d\u2019una [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":15486,"template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[181],"class_list":["post-15505","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-exposicions","cat_exposicions"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Paysage Mir\u00f3 al Casal Solleric, Palma 2025<\/title>\n<meta name=\"description\" content=\"Entrada lliure a l&#039;exposici\u00f3 de Joan Mir\u00f3 al Casal Solleric. Pintura i escultura dialoguen del 2 d\u2019agost al 9 de novembre de 2025.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/visitpalma.com\/ca\/event\/paysage-miro-el-color-i-la-seva-ombra\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Paysage Mir\u00f3 al Casal Solleric, Palma 2025\" \/>\n<meta property=\"og:description\" content=\"Entrada lliure a l&#039;exposici\u00f3 de Joan Mir\u00f3 al Casal Solleric. Pintura i escultura dialoguen del 2 d\u2019agost al 9 de novembre de 2025.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/visitpalma.com\/ca\/event\/paysage-miro-el-color-i-la-seva-ombra\/\" \/>\n<meta property=\"og:site_name\" content=\"Visit Palma\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/passionforpalma\" \/>\n<meta property=\"og:image\" content=\"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/07\/Paysage-Miro-El-color-i-la-seva-ombra-Palma-20251.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"812\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@passionforpalma\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/event\\\/paysage-miro-el-color-i-la-seva-ombra\\\/\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/event\\\/paysage-miro-el-color-i-la-seva-ombra\\\/\",\"name\":\"Paysage Mir\u00f3 al Casal Solleric, Palma 2025\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/event\\\/paysage-miro-el-color-i-la-seva-ombra\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/event\\\/paysage-miro-el-color-i-la-seva-ombra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Paysage-Miro-El-color-i-la-seva-ombra-Palma-20251.jpg\",\"datePublished\":\"2025-07-25T10:23:50+00:00\",\"description\":\"Entrada lliure a l'exposici\u00f3 de Joan Mir\u00f3 al Casal Solleric. Pintura i escultura dialoguen del 2 d\u2019agost al 9 de novembre de 2025.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/event\\\/paysage-miro-el-color-i-la-seva-ombra\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/visitpalma.com\\\/ca\\\/event\\\/paysage-miro-el-color-i-la-seva-ombra\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/event\\\/paysage-miro-el-color-i-la-seva-ombra\\\/#primaryimage\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Paysage-Miro-El-color-i-la-seva-ombra-Palma-20251.jpg\",\"contentUrl\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Paysage-Miro-El-color-i-la-seva-ombra-Palma-20251.jpg\",\"width\":812,\"height\":500,\"caption\":\"Paysage-Miro-El-color-i-la-seva-ombra-Palma-2025\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/event\\\/paysage-miro-el-color-i-la-seva-ombra\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Esdeveniments\",\"item\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Paysage Mir\u00f3: El color i la seva ombra\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/\",\"name\":\"Visit Palma\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/#organization\",\"name\":\"Fundaci\u00f3n Turismo Palma de Mallorca 365\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Logo-Passion-for-Palma-de-Mallorca.svg\",\"contentUrl\":\"https:\\\/\\\/visitpalma.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Logo-Passion-for-Palma-de-Mallorca.svg\",\"width\":377,\"height\":377,\"caption\":\"Fundaci\u00f3n Turismo Palma de Mallorca 365\"},\"image\":{\"@id\":\"https:\\\/\\\/visitpalma.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/passionforpalma\",\"https:\\\/\\\/x.com\\\/passionforpalma\",\"https:\\\/\\\/www.instagram.com\\\/passionforpalma_\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCALF2N1FRnmAZYBttkQjedA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Paysage Mir\u00f3 al Casal Solleric, Palma 2025","description":"Entrada lliure a l'exposici\u00f3 de Joan Mir\u00f3 al Casal Solleric. Pintura i escultura dialoguen del 2 d\u2019agost al 9 de novembre de 2025.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/visitpalma.com\/ca\/event\/paysage-miro-el-color-i-la-seva-ombra\/","og_locale":"ca_ES","og_type":"article","og_title":"Paysage Mir\u00f3 al Casal Solleric, Palma 2025","og_description":"Entrada lliure a l'exposici\u00f3 de Joan Mir\u00f3 al Casal Solleric. Pintura i escultura dialoguen del 2 d\u2019agost al 9 de novembre de 2025.","og_url":"https:\/\/visitpalma.com\/ca\/event\/paysage-miro-el-color-i-la-seva-ombra\/","og_site_name":"Visit Palma","article_publisher":"https:\/\/www.facebook.com\/passionforpalma","og_image":[{"width":812,"height":500,"url":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/07\/Paysage-Miro-El-color-i-la-seva-ombra-Palma-20251.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@passionforpalma","twitter_misc":{"Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/visitpalma.com\/ca\/event\/paysage-miro-el-color-i-la-seva-ombra\/","url":"https:\/\/visitpalma.com\/ca\/event\/paysage-miro-el-color-i-la-seva-ombra\/","name":"Paysage Mir\u00f3 al Casal Solleric, Palma 2025","isPartOf":{"@id":"https:\/\/visitpalma.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/visitpalma.com\/ca\/event\/paysage-miro-el-color-i-la-seva-ombra\/#primaryimage"},"image":{"@id":"https:\/\/visitpalma.com\/ca\/event\/paysage-miro-el-color-i-la-seva-ombra\/#primaryimage"},"thumbnailUrl":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/07\/Paysage-Miro-El-color-i-la-seva-ombra-Palma-20251.jpg","datePublished":"2025-07-25T10:23:50+00:00","description":"Entrada lliure a l'exposici\u00f3 de Joan Mir\u00f3 al Casal Solleric. Pintura i escultura dialoguen del 2 d\u2019agost al 9 de novembre de 2025.","breadcrumb":{"@id":"https:\/\/visitpalma.com\/ca\/event\/paysage-miro-el-color-i-la-seva-ombra\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/visitpalma.com\/ca\/event\/paysage-miro-el-color-i-la-seva-ombra\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/visitpalma.com\/ca\/event\/paysage-miro-el-color-i-la-seva-ombra\/#primaryimage","url":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/07\/Paysage-Miro-El-color-i-la-seva-ombra-Palma-20251.jpg","contentUrl":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/07\/Paysage-Miro-El-color-i-la-seva-ombra-Palma-20251.jpg","width":812,"height":500,"caption":"Paysage-Miro-El-color-i-la-seva-ombra-Palma-2025"},{"@type":"BreadcrumbList","@id":"https:\/\/visitpalma.com\/ca\/event\/paysage-miro-el-color-i-la-seva-ombra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/visitpalma.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Esdeveniments","item":"https:\/\/visitpalma.com\/ca\/events\/"},{"@type":"ListItem","position":3,"name":"Paysage Mir\u00f3: El color i la seva ombra"}]},{"@type":"WebSite","@id":"https:\/\/visitpalma.com\/ca\/#website","url":"https:\/\/visitpalma.com\/ca\/","name":"Visit Palma","description":"","publisher":{"@id":"https:\/\/visitpalma.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/visitpalma.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/visitpalma.com\/ca\/#organization","name":"Fundaci\u00f3n Turismo Palma de Mallorca 365","url":"https:\/\/visitpalma.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/visitpalma.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/05\/Logo-Passion-for-Palma-de-Mallorca.svg","contentUrl":"https:\/\/visitpalma.com\/wp-content\/uploads\/2025\/05\/Logo-Passion-for-Palma-de-Mallorca.svg","width":377,"height":377,"caption":"Fundaci\u00f3n Turismo Palma de Mallorca 365"},"image":{"@id":"https:\/\/visitpalma.com\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/passionforpalma","https:\/\/x.com\/passionforpalma","https:\/\/www.instagram.com\/passionforpalma_\/","https:\/\/www.youtube.com\/channel\/UCALF2N1FRnmAZYBttkQjedA"]}]}},"_links":{"self":[{"href":"https:\/\/visitpalma.com\/ca\/wp-json\/wp\/v2\/tribe_events\/15505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visitpalma.com\/ca\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/visitpalma.com\/ca\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/visitpalma.com\/ca\/wp-json\/wp\/v2\/users\/4"}],"version-history":[{"count":0,"href":"https:\/\/visitpalma.com\/ca\/wp-json\/wp\/v2\/tribe_events\/15505\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visitpalma.com\/ca\/wp-json\/wp\/v2\/media\/15486"}],"wp:attachment":[{"href":"https:\/\/visitpalma.com\/ca\/wp-json\/wp\/v2\/media?parent=15505"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visitpalma.com\/ca\/wp-json\/wp\/v2\/tags?post=15505"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/visitpalma.com\/ca\/wp-json\/wp\/v2\/tribe_events_cat?post=15505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}